{"id":22808,"date":"2020-06-23T09:32:47","date_gmt":"2020-06-23T12:32:47","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22808"},"modified":"2020-06-23T09:32:47","modified_gmt":"2020-06-23T12:32:47","slug":"acontecer-tres-dicas-de-emprego","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/acontecer-tres-dicas-de-emprego\/","title":{"rendered":"Acontecer: tr\u00eas dicas de emprego"},"content":{"rendered":"<p>As palavras, como as pessoas, t\u00eam manias. Combinam. Brigam. Fazem exig\u00eancias. Armam ciladas. Um verbo cheio de caprichos \u00e9\u00a0o <em>acontecer<\/em>. Elitista, ele tem poucos empregos. E quase nenhum amigo. Mas, por arte do destino, os colunistas sociais o adotaram. A moda se espalhou como not\u00edcia ruim. O pobre virou praga. Tudo acontece. At\u00e9 pessoas: Fabr\u00edcio Queiroz<em> est\u00e1 acontecendo no inqu\u00e9rito das rachadinhas. O<\/em> <em>casamento acontece na catedral. <\/em>O <em>show acontece \u00e0s 22h. <\/em>E por a\u00ed vai. Violentado, o verbo vira a cara. Esperneia. E se vinga. Deixa mal quem abusa dele. Diz que o atrevido sofre de pobreza de vocabul\u00e1rio. Para n\u00e3o cair na boca do povo, s\u00f3\u00a0h\u00e1\u00a0uma sa\u00edda: empreg\u00e1-lo na acep\u00e7\u00e3o de <em>suceder de repente. <\/em><\/p>\n<p><strong>Superdicas<\/strong><\/p>\n<p>1. Acontecer tem a acep\u00e7\u00e3o de ocorrer de repente: <em>Caso acontecesse o ataque, haveria muitos mortos<\/em>.<\/p>\n<p>2. O verbo \u00e9 bem-vindo na companhia dos pronomes indefinidos (tudo, nada, todos), demonstrativos (este, isto, aquilo) e o interrogativo (que): <em>Tudo pode acontecer durante o conflito. Aquilo n\u00e3o aconteceu de uma hora para outra. O que aconteceu<\/em>?<\/p>\n<p>3. N\u00e3o use acontecer no sentido de ser, haver, realizar-se, ocorrer, suceder, existir, verificar-se, dar-se, estar marcado para: <em>O<\/em> <em>show acontece<\/em> (est\u00e1 marcado para) <em>\u00e0s 22h<\/em>. <em>O festival<\/em> <em>aconteceu<\/em> (ocorreu) <em>no ano passado. Acontecem<\/em> (ocorrem<em>) injusti\u00e7as no concurso. As provas est\u00e3o previstas para acontecer em setembro<\/em> (previstas para setembro).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As palavras, como as pessoas, t\u00eam manias. Combinam. Brigam. Fazem exig\u00eancias. Armam ciladas. Um verbo cheio de caprichos \u00e9\u00a0o acontecer. Elitista, ele tem poucos empregos. E quase nenhum amigo. Mas, por arte do destino, os colunistas sociais o adotaram. A moda se espalhou como not\u00edcia ruim. O pobre virou praga. Tudo acontece. At\u00e9 pessoas: Fabr\u00edcio Queiroz est\u00e1 acontecendo no inqu\u00e9rito das rachadinhas. O casamento acontece [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[450,768],"class_list":["post-22808","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-acontecer","tag-emprego"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22808"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22808\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}