{"id":22719,"date":"2020-06-12T07:03:33","date_gmt":"2020-06-12T10:03:33","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22719"},"modified":"2020-06-12T07:03:33","modified_gmt":"2020-06-12T10:03:33","slug":"camoes-sobre-o-amor","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/camoes-sobre-o-amor\/","title":{"rendered":"Cam\u00f5es sobre o amor"},"content":{"rendered":"<p>\u201cAmor \u00e9 fogo que arde sem se ver,<\/p>\n<p>\u00e9 ferida que d\u00f3i, e n\u00e3o se sente;<\/p>\n<p>\u00e9 um contentamento descontente,<\/p>\n<p>\u00e9 dor que desatina sem doer.\u201d<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAmor \u00e9 fogo que arde sem se ver, \u00e9 ferida que d\u00f3i, e n\u00e3o se sente; \u00e9 um contentamento descontente, \u00e9 dor que desatina sem doer.\u201d &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3349,4547,41,4548],"class_list":["post-22719","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-amor","tag-camoes","tag-citacao","tag-fogo-que-arde"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22719"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22719\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}