{"id":22699,"date":"2020-06-08T10:50:07","date_gmt":"2020-06-08T13:50:07","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22699"},"modified":"2020-06-08T10:50:07","modified_gmt":"2020-06-08T13:50:07","slug":"enquete-na-internet-10-erros-que-mais-incomodam-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/enquete-na-internet-10-erros-que-mais-incomodam-2\/","title":{"rendered":"Enquete na internet: 10 erros que mais incomodam (2)"},"content":{"rendered":"<p>Postei na internet o pedido: &#8220;Cite um erro de portugu\u00eas que mais incomoda voc\u00ea&#8221;.\u00a0 Seguidores responderam com contribui\u00e7\u00f5es variadas. A enquete ficou pra l\u00e1 de rica. Eis a segunda rela\u00e7\u00e3o.<\/p>\n<p><strong>Mais \/ mas <\/strong><\/p>\n<p><strong>Mais<\/strong> = o contr\u00e1rio de <strong>menos<\/strong>: <em>Trabalho mais (menos) que Maria. <\/em><\/p>\n<p><strong>Mas<\/strong> = conjun\u00e7\u00e3o adversativa. Exprime ideia oposta, contr\u00e1ria \u00e0 l\u00f3gica: <em>Ele estudou muito, mas n\u00e3o passou na prova<\/em>. (Se estudou muito, deveria ter passado, mas&#8230;)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A ver \/ haver<\/strong><\/p>\n<p><strong>A ver<\/strong> = ter rela\u00e7\u00e3o: <em>Minha hist\u00f3ria tem tudo a ver com a de Paulo. Este fato n\u00e3o tem nada a ver com aquele. <\/em><\/p>\n<p><strong>Haver<\/strong> = verbo: <em>Segundo a ONU, no mundo deve haver 60 milh\u00f5es de crian\u00e7as sem acesso \u00e0 internet. O emprego do verbo haver oferece dificuldades aos falante. Vai haver aula?<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acento \/ assento<\/strong><\/p>\n<p><strong>Acento<\/strong> = sinal gr\u00e1fico: agudo (\u00b4), grave (\u00e0) e circunflexo (^).<\/p>\n<p><strong>Assento<\/strong> = lugar onde se senta: <em>assento preferencial, assento na ABL, assento dianteiro<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A gente \/ agente<\/strong><\/p>\n<p><strong>A gente<\/strong> = n\u00f3s. Exige o verbo na 3\u00aa pessoa do singular: <em>A gente vai sair mais cedo. Quer sair com a gente? A gente quer ficar em casa, mas nem sempre pode.<\/em><\/p>\n<p><strong>Agente<\/strong> = ser que executa uma a\u00e7\u00e3o: <em>agente penitenci\u00e1rio, agente secreto, agente da passiva.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00d3culos<\/strong><\/p>\n<p><strong>\u00d3culos<\/strong> s\u00f3 se usa no plural: <em>meus \u00f3culos, \u00f3culos escuros, \u00f3culos importados.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Privil\u00e9gio<\/strong><\/p>\n<p>Pr<strong>i<\/strong>v<strong>i<\/strong>l\u00e9gio tem dose dupla de i. Previl\u00e9gio n\u00e3o tem vez. X\u00f4!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Com certeza<\/strong><\/p>\n<p><strong>Com certeza<\/strong> se escreve assim, um l\u00e1 e outro c\u00e1. Concerteza n\u00e3o existe.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Subs\u00eddio<\/strong><\/p>\n<p>Sub<strong>s<\/strong>\u00eddio joga no time de sub<strong>s<\/strong>olo. Com a duplinha, o som z n\u00e3o tem vez. X\u00f4!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Estupro<\/strong><\/p>\n<p><strong>Estupro<\/strong> se escreve assim. O <strong>r<\/strong> fica na \u00faltima s\u00edlaba. Muitos o mudam de lugar. Escrevem estrupo. Nada feito.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Por hora \/ por ora<\/strong><\/p>\n<p><strong>Por hora<\/strong> = a cada 60 minutos: <em>Recebe R$ 100 por hora de trabalho.<\/em><\/p>\n<p><strong>Por ora<\/strong> = por agora: <em>Por ora, a alternativa \u00e9 ficar em casa.<\/em> <em>Por ora, a velocidade m\u00e1xima na via \u00e9 de 60km por hora<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postei na internet o pedido: &#8220;Cite um erro de portugu\u00eas que mais incomoda voc\u00ea&#8221;.\u00a0 Seguidores responderam com contribui\u00e7\u00f5es variadas. A enquete ficou pra l\u00e1 de rica. Eis a segunda rela\u00e7\u00e3o. Mais \/ mas Mais = o contr\u00e1rio de menos: Trabalho mais (menos) que Maria. Mas = conjun\u00e7\u00e3o adversativa. Exprime ideia oposta, contr\u00e1ria \u00e0 l\u00f3gica: Ele estudou muito, mas n\u00e3o passou na prova. (Se estudou muito, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[4533,1070,172,294,4534,386,4535,2260,171,2836,2835,277,4536,4085,4537],"class_list":["post-22699","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-10-erros-incomodam","tag-a-gente","tag-a-ver","tag-acento","tag-agente","tag-assento","tag-com-certeza","tag-estupro","tag-haver","tag-mais","tag-mas","tag-oculos","tag-por-hora","tag-por-ora","tag-privilegio"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22699"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22699\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}