{"id":22557,"date":"2020-05-24T10:17:21","date_gmt":"2020-05-24T13:17:21","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22557"},"modified":"2020-05-24T10:17:21","modified_gmt":"2020-05-24T13:17:21","slug":"etimologia-cinemateca-videoteca-cia","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/etimologia-cinemateca-videoteca-cia\/","title":{"rendered":"Etimologia: cinemateca, videoteca &amp; cia."},"content":{"rendered":"<p>Cinemateca rima com biblioteca, videoteca, discoteca, brinquedoteca. Reparou? Todas as palavras terminam com <em>teca.<\/em> As quatro letrinhas querem dizer isto: lugar fechado onde se guarda um mont\u00e3o de alguma coisa. Que coisa? Cinemateca guarda filmes. Biblioteca, livros. Videoteca, fitas. Cinemateca, filmes. E brinquedoteca? Est\u00e1 na cara \u2014 brinquedos. Vamos \u00e0 farra?<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinemateca rima com biblioteca, videoteca, discoteca, brinquedoteca. Reparou? Todas as palavras terminam com teca. As quatro letrinhas querem dizer isto: lugar fechado onde se guarda um mont\u00e3o de alguma coisa. Que coisa? Cinemateca guarda filmes. Biblioteca, livros. Videoteca, fitas. Cinemateca, filmes. E brinquedoteca? Est\u00e1 na cara \u2014 brinquedos. Vamos \u00e0 farra? \u00a0 \u00a0<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3715,4468,4469,4470,145,4471],"class_list":["post-22557","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-biblioteca","tag-brinquedoteca","tag-cinemetaeca","tag-eca","tag-etimologia","tag-videoteca"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22557"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22557\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}