{"id":22449,"date":"2020-05-14T10:42:18","date_gmt":"2020-05-14T13:42:18","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/dad\/?p=22449"},"modified":"2020-05-14T10:42:18","modified_gmt":"2020-05-14T13:42:18","slug":"candango-origem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/candango-origem\/","title":{"rendered":"Candango: origem"},"content":{"rendered":"<p>O oper\u00e1rio que trabalhava na constru\u00e7\u00e3o de Bras\u00edlia se chamava candango. A designa\u00e7\u00e3o era pejorativa. O dicion\u00e1rio explica que a palavra nasceu na \u00c1frica. Era como os escravos se referiam aos portugueses que traficavam pessoas \u2014 gente ruim, ordin\u00e1ria, perversa.<\/p>\n<p>No come\u00e7o, candangos eram os nordestinos, a maior parte da m\u00e3o de obra bra\u00e7al. Depois passou a denominar os pioneiros que chegaram nos prim\u00f3rdios da capital. Por fim, se tornou sin\u00f4nimo de\u00a0brasiliense. Com muito orgulho sim, senhor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O oper\u00e1rio que trabalhava na constru\u00e7\u00e3o de Bras\u00edlia se chamava candango. A designa\u00e7\u00e3o era pejorativa. O dicion\u00e1rio explica que a palavra nasceu na \u00c1frica. Era como os escravos se referiam aos portugueses que traficavam pessoas \u2014 gente ruim, ordin\u00e1ria, perversa. No come\u00e7o, candangos eram os nordestinos, a maior parte da m\u00e3o de obra bra\u00e7al. Depois passou a denominar os pioneiros que chegaram nos prim\u00f3rdios da [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1662,4420,4421,145],"class_list":["post-22449","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-brasilia","tag-brasiliense","tag-candango","tag-etimologia"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=22449"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/22449\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=22449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=22449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=22449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}