{"id":21888,"date":"2020-02-25T07:30:59","date_gmt":"2020-02-25T10:30:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21888"},"modified":"2020-02-25T07:30:59","modified_gmt":"2020-02-25T10:30:59","slug":"as-mascaras-e-as-consoantes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/as-mascaras-e-as-consoantes\/","title":{"rendered":"As m\u00e1scaras e as consoantes"},"content":{"rendered":"<p>Consoantes t\u00eam v\u00e1rias leis. Uma delas: quanto mais confus\u00e3o melhor. Pra obedecer \u00e0 determina\u00e7\u00e3o t\u00e3o divertida, nada mais adequado que usar e abusar das m\u00e1scaras. Com elas, uma letra multiplica os sons. E, claro, d\u00e1 n\u00f3 nos miolos dos pobres mortais. Vale o exemplo do <strong>x<\/strong>. A danadinha adora trocar os disfarces. Em certas palavras, pronuncia-se ch (enxoval). Em outras, z (exame). Em outras, ainda, s (excel\u00eancia). Chega? N\u00e3o. H\u00e1 os casos em que a gloriosa soa ks (t\u00e1xi). Ufa!<\/p>\n<p>O <strong>s<\/strong>, ent\u00e3o, abusa. Salta de galho em galho com tal destreza que faz inveja a Tarz\u00e3. No come\u00e7o da palavra, soa c\u00ea (sala). Entre duas vogais, z (pesquisa). \u00c9 a\u00ed que a porca torce o rabo. Caprichoso, o vers\u00e1til quer manter a originalidade entre duas vogais. Imposs\u00edvel? Ele d\u00e1 um jeito. Apresenta-se em dose dupla (massa). Mant\u00e9m a originalidade tamb\u00e9m quando aparece entre vogal e consoante (cansar). Ops! Em tr\u00e2nsito, ele se exibe entre n e i. Mas soa z. Quem entende? Calma. \u00c9 carnaval.<\/p>\n<p>Uma ilustre senhora tem fasc\u00ednio por fantasias, m\u00e1scaras e badulaques. Quem \u00e9? \u00c9 a letra <strong>c<\/strong>. Seguida de <strong>a<\/strong>, <strong>o<\/strong> e <strong>u<\/strong>, soa k (casa, coisa, cuia). Seguida de <strong>e<\/strong> e <strong>i<\/strong>, pronuncia-se c\u00ea (cedo, cidade). Partid\u00e1rio do s, o c teima em soar c\u00ea quando seguido de <strong>a<\/strong>, <strong>o<\/strong>, <strong>u<\/strong>. Recorre, ent\u00e3o, \u00e0 marca que faz o Brasil Brasil. D\u00e1 um jeito. Cal\u00e7a um sapatinho e ganha a parada (cal\u00e7ado, a\u00e7o, a\u00e7ude).<\/p>\n<p>&nbsp;<\/p>\n<p>Moral da hist\u00f3ria<\/p>\n<p>M\u00e1rio Quintana disse que a mentira \u00e9 a verdade que se esqueceu de acontecer. No carnaval das letras, a mentira acontece.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consoantes t\u00eam v\u00e1rias leis. Uma delas: quanto mais confus\u00e3o melhor. Pra obedecer \u00e0 determina\u00e7\u00e3o t\u00e3o divertida, nada mais adequado que usar e abusar das m\u00e1scaras. Com elas, uma letra multiplica os sons. E, claro, d\u00e1 n\u00f3 nos miolos dos pobres mortais. Vale o exemplo do x. A danadinha adora trocar os disfarces. Em certas palavras, pronuncia-se ch (enxoval). Em outras, z (exame). Em outras, ainda, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[4148,2902,4147,2903,83,272],"class_list":["post-21888","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-c","tag-consoantes","tag-fonemas","tag-mascaras","tag-s","tag-x"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21888"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21888\/revisions"}],"predecessor-version":[{"id":21889,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21888\/revisions\/21889"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}