{"id":21814,"date":"2020-02-16T07:59:50","date_gmt":"2020-02-16T10:59:50","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21814"},"modified":"2020-02-16T07:59:50","modified_gmt":"2020-02-16T10:59:50","slug":"ambiguidade-e-isto","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ambiguidade-e-isto\/","title":{"rendered":"Ambiguidade \u00e9 isto"},"content":{"rendered":"<p>Apar\u00edcio Torelli ficou conhecido como Bar\u00e3o de Itarar\u00e9. Bem-humorado, soltava piadas a torto e a direito. Para ele, n\u00e3o havia situa\u00e7\u00e3o s\u00e9ria. Toda hora era hora pra provocar risos.<\/p>\n<p>Um dia, estava fazendo a prova oral. Disputava uma vaga na faculdade de medicina. O examinador, s\u00e9rio, perguntou:<\/p>\n<p>\u2014 Quantos rins n\u00f3s temos?<\/p>\n<p>\u2014 Quatro, respondeu Apar\u00edcio sem pestanejar.<\/p>\n<p>O professor perdeu a fala. Gargalhadas explodiram c\u00e1, l\u00e1, acol\u00e1. \u00a0S\u00e9rio, Apar\u00edcio explicou:<\/p>\n<p>\u2014 Dois meus e dois seus.<\/p>\n<p>O mestre n\u00e3o deixou por menos. Querendo fazer gra\u00e7a, pediu \u00e0 copeira:<\/p>\n<p>\u2014 Um feixe de capim&#8230;<\/p>\n<p>Apar\u00edcio foi mais r\u00e1pido:<\/p>\n<p>\u2014 Pra mim um cafezinho.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apar\u00edcio Torelli ficou conhecido como Bar\u00e3o de Itarar\u00e9. Bem-humorado, soltava piadas a torto e a direito. Para ele, n\u00e3o havia situa\u00e7\u00e3o s\u00e9ria. Toda hora era hora pra provocar risos. Um dia, estava fazendo a prova oral. Disputava uma vaga na faculdade de medicina. O examinador, s\u00e9rio, perguntou: \u2014 Quantos rins n\u00f3s temos? \u2014 Quatro, respondeu Apar\u00edcio sem pestanejar. O professor perdeu a fala. Gargalhadas explodiram [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[269,4118,3600],"class_list":["post-21814","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-ambiguidade","tag-barao-de-irarare","tag-rins"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21814"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21814\/revisions"}],"predecessor-version":[{"id":21815,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21814\/revisions\/21815"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}