{"id":21758,"date":"2020-02-09T08:04:56","date_gmt":"2020-02-09T11:04:56","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21758"},"modified":"2020-02-09T08:04:56","modified_gmt":"2020-02-09T11:04:56","slug":"pleonasmo-fato-real-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/pleonasmo-fato-real-2\/","title":{"rendered":"Pleonasmo: fato real"},"content":{"rendered":"<p>Filme baseado em fatos reais? \u00c9 senhor pleonasmo. Todo fato \u00e9 real. Basta fato. Se quiser usar o adjetivo, mude o substantivo: <em>filme baseado em hist\u00f3ria real.<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filme baseado em fatos reais? \u00c9 senhor pleonasmo. Todo fato \u00e9 real. Basta fato. Se quiser usar o adjetivo, mude o substantivo: filme baseado em hist\u00f3ria real. &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[4095,160],"class_list":["post-21758","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-fato-real","tag-pleonasmo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21758"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21758\/revisions"}],"predecessor-version":[{"id":21759,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21758\/revisions\/21759"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}