{"id":21740,"date":"2020-02-07T16:47:16","date_gmt":"2020-02-07T19:47:16","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21740"},"modified":"2020-02-07T16:47:16","modified_gmt":"2020-02-07T19:47:16","slug":"hifen-mal-estar-e-bem-estar","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/hifen-mal-estar-e-bem-estar\/","title":{"rendered":"H\u00edfen: mal-estar e bem-estar"},"content":{"rendered":"<p>O professor de Bras\u00edlia que tomou um suco de uva e sentiu fortes dores foi para o hospital. L\u00e1, mandou um \u00e1udio para o amigos. Falou de mal-estar crescente. Ao transcrever o di\u00e1logo, jornais escreveram mal estar. Bobearam. Mal-estar se grafa com h\u00edfen. Bem-estar tamb\u00e9m.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O professor de Bras\u00edlia que tomou um suco de uva e sentiu fortes dores foi para o hospital. L\u00e1, mandou um \u00e1udio para o amigos. Falou de mal-estar crescente. Ao transcrever o di\u00e1logo, jornais escreveram mal estar. Bobearam. Mal-estar se grafa com h\u00edfen. Bem-estar tamb\u00e9m.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[4087],"class_list":["post-21740","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-hifen-mal-estar-e-bem-estar"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21740"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21740\/revisions"}],"predecessor-version":[{"id":21741,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21740\/revisions\/21741"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}