{"id":21508,"date":"2020-01-01T11:11:15","date_gmt":"2020-01-01T14:11:15","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21508"},"modified":"2020-01-01T11:11:15","modified_gmt":"2020-01-01T14:11:15","slug":"ponto-numerais","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ponto-numerais\/","title":{"rendered":"Ponto: numerais"},"content":{"rendered":"<p>Ops! Ao escrever os n\u00fameros, usamos ponto a cada tr\u00eas algarismos \u2013 1.426, 12.122, 3.342.600. Mas, ao indicar o ano, a hist\u00f3ria muda de enredo. Vem tudo coladinho. Assim: <em>Ele nasceu em 1946. Trabalha em S\u00e3o Paulo desde 2000. Em 2014, o Brasil foi sede da Copa do Mundo. O ano de 20202 promete boas not\u00edcias.<br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ops! Ao escrever os n\u00fameros, usamos ponto a cada tr\u00eas algarismos \u2013 1.426, 12.122, 3.342.600. Mas, ao indicar o ano, a hist\u00f3ria muda de enredo. Vem tudo coladinho. Assim: Ele nasceu em 1946. Trabalha em S\u00e3o Paulo desde 2000. Em 2014, o Brasil foi sede da Copa do Mundo. O ano de 20202 promete boas not\u00edcias.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[2343,70,241,836],"class_list":["post-21508","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-ano","tag-grafia","tag-numeral","tag-ponto"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21508"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21508\/revisions"}],"predecessor-version":[{"id":21509,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21508\/revisions\/21509"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}