{"id":21231,"date":"2019-11-15T10:01:21","date_gmt":"2019-11-15T13:01:21","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=21231"},"modified":"2019-11-15T10:01:21","modified_gmt":"2019-11-15T13:01:21","slug":"russo-e-ruco-emprego","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/russo-e-ruco-emprego\/","title":{"rendered":"Russo e ru\u00e7o: emprego"},"content":{"rendered":"<p><strong>Russo<\/strong>, o origin\u00e1rio da R\u00fassia, forma compostos. Olho na grafia! Os adjetivos p\u00e1trios pedem h\u00edfen (russo-americano, russo-brasileiro, russo-germ\u00e2nico). Os demais compostos mandam o tracinho pras cucuias: <em>russofobia (pavor de russo), russ\u00f3filo (amig\u00e3o dos russos).<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>T\u00e1 ru\u00e7o<\/strong><\/p>\n<p>Sem confus\u00e3o, marinheiros de poucas viagens. Russo e ru\u00e7o n\u00e3o se conhecem nem de elevador. Russo \u00e9 o natural ou origin\u00e1rio da R\u00fassia. Ru\u00e7o quer dizer pardacento, complicado: <em>A coisa est\u00e1 ru\u00e7a. O conflito ficou ru\u00e7o. Os russos adoram vodca, mas ficam longe de situa\u00e7\u00f5es ru\u00e7as.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russo, o origin\u00e1rio da R\u00fassia, forma compostos. Olho na grafia! Os adjetivos p\u00e1trios pedem h\u00edfen (russo-americano, russo-brasileiro, russo-germ\u00e2nico). Os demais compostos mandam o tracinho pras cucuias: russofobia (pavor de russo), russ\u00f3filo (amig\u00e3o dos russos). \u00a0T\u00e1 ru\u00e7o Sem confus\u00e3o, marinheiros de poucas viagens. Russo e ru\u00e7o n\u00e3o se conhecem nem de elevador. Russo \u00e9 o natural ou origin\u00e1rio da R\u00fassia. Ru\u00e7o quer dizer pardacento, complicado: A [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[70,76,2017,2018],"class_list":["post-21231","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-grafia","tag-hifen","tag-ruco","tag-russo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=21231"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21231\/revisions"}],"predecessor-version":[{"id":21232,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/21231\/revisions\/21232"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=21231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=21231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=21231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}