{"id":20910,"date":"2019-10-08T08:22:50","date_gmt":"2019-10-08T11:22:50","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=20910"},"modified":"2019-10-08T08:22:50","modified_gmt":"2019-10-08T11:22:50","slug":"aos-domingos-nos-domingos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/aos-domingos-nos-domingos\/","title":{"rendered":"Aos domingos? Nos domingos?"},"content":{"rendered":"<p><strong>Aos domingos<\/strong> = <em>todos os domingos: Vou \u00e0 missa aos domingos. H\u00e1 m\u00e9dicos que preferem dar plant\u00e3o aos domingos. O com\u00e9rcio abre aos domingos.<\/em> Os demais dias da semana seguem a mesma regra. Pedem a preposi\u00e7\u00e3o <em>a<\/em> quando indicam a\u00e7\u00e3o que se repete: <em>Os museus fecham \u00e0s segundas-feiras (todas as segundas). Estudo ingl\u00eas \u00e0s ter\u00e7as e sextas. Costumo ir \u00e0 livraria aos s\u00e1bados<\/em>.<\/p>\n<p><strong>No domingo<\/strong><em> (no s\u00e1bado, na segunda)<\/em> = o fato ocorre uma vez ou de vez em quando: <em>Rafael se casa no s\u00e1bado. Jo\u00e3o Marcelo nasceu na sexta-feira. Quero ir ao cinema na quarta. <\/em>Em bom portugu\u00eas<em>: <\/em>Se a a\u00e7\u00e3o se repete, \u00e9 a vez da preposi\u00e7\u00e3o <em>a<\/em>. Se ocorre uma vez ou de vez em quando, em.<\/p>\n<p><strong>Nunca aos domingos<\/strong><\/p>\n<p>Sidney Lima<\/p>\n<p>\u00d3, beija-me numa segunda, segunda, segunda<\/p>\n<p>Que \u00e9 muito, muito bom<\/p>\n<p>\u00d3, beija-me tamb\u00e9m na ter\u00e7a, na ter\u00e7a, na ter\u00e7a<\/p>\n<p>De todo o cora\u00e7\u00e3o!<\/p>\n<p>\u00c9 gostos\u00edssimo na quarta, na quinta, na sexta<\/p>\n<p>No s\u00e1bado beijar!<\/p>\n<p>Mas nunca, nunca no domingo, domingo, domingo<\/p>\n<p>Que \u00e9 dia de folgar!<\/p>\n<p>Com vento frio ou com Sol ardente<\/p>\n<p>Com seu beijo quente, chego a desmaiar<\/p>\n<p>Mas, por favor, nunca aos domingos<\/p>\n<p>Venha me beijar, nem falar de amor!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos domingos = todos os domingos: Vou \u00e0 missa aos domingos. H\u00e1 m\u00e9dicos que preferem dar plant\u00e3o aos domingos. O com\u00e9rcio abre aos domingos. Os demais dias da semana seguem a mesma regra. Pedem a preposi\u00e7\u00e3o a quando indicam a\u00e7\u00e3o que se repete: Os museus fecham \u00e0s segundas-feiras (todas as segundas). Estudo ingl\u00eas \u00e0s ter\u00e7as e sextas. Costumo ir \u00e0 livraria aos s\u00e1bados. No domingo [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1308,1159,2802,1160,252],"class_list":["post-20910","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-a","tag-aos-domingos","tag-em","tag-nos-domingos","tag-preposicao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=20910"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20910\/revisions"}],"predecessor-version":[{"id":20923,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20910\/revisions\/20923"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=20910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=20910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=20910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}