{"id":20832,"date":"2019-09-27T09:10:39","date_gmt":"2019-09-27T12:10:39","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=20832"},"modified":"2019-09-27T09:10:39","modified_gmt":"2019-09-27T12:10:39","slug":"rima-na-prosa-xo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/rima-na-prosa-xo\/","title":{"rendered":"Rima na prosa? X\u00f4"},"content":{"rendered":"<p>A l\u00edngua encanta. Harmonias e ritmos seduzem ouvidos e arrebatam cora\u00e7\u00f5es. Como chegar l\u00e1? N\u00e3o h\u00e1 necessidade de m\u00e1gicas. Basta usar os recursos do c\u00f3digo \u2014 organizar as palavras de tal forma que a frase ganhe flu\u00eancia e ritmo. A melhor pista: ler o texto em voz alta. O que escapa aos olhos grita aos ouvidos.<\/p>\n<p>\u00c9 o caso do eco. A rima \u00e9 qualidade da poesia, mas defeito na prosa. A \u00a0repeti\u00e7\u00e3o de sons iguais ou semelhantes pede provid\u00eancias:<\/p>\n<ol>\n<li><em>Houve <strong>confus\u00e3o<\/strong> na <strong>reuni\u00e3o<\/strong> da diretoria. Feito o estrago, n\u00e3o houve como impedir a <strong>divulga\u00e7\u00e3o<\/strong> do fato. Agora se teme que os s\u00f3cios exijam a <strong>elucida\u00e7\u00e3o<\/strong> dos pormenores.\u00a0\u00a0\u00a0 <\/em><\/li>\n<\/ol>\n<p><em>\u00a0<\/em>Tantos \u00e3os retumbam como trov\u00e3o. Mesmo em sil\u00eancio, saltam aos olhos e ecoam no ouvido interno. Melhor reduzir a presen\u00e7a da dupla barulhenta: <em>Houve tumulto no encontro da diretoria. Feito o estrago, foi imposs\u00edvel evitar a divulga\u00e7\u00e3o do fato. Agora se teme que os s\u00f3cios exijam que se elucidem os pormenores.<\/em><\/p>\n<p><em>\u00a0\u00a0\u00a0 2. O Plano <strong>Real<\/strong> acabou com a infla\u00e7\u00e3o considerada <strong>mortal<\/strong> para o trabalhador.<br \/>\n<\/em><br \/>\nNada feito. O ouvido reclama. Vamos ao troca-troca: O Plano Real acabou com a infla\u00e7\u00e3o que mata a economia do trabalhador.<\/p>\n<p><em>\u00a0\u00a0 3. O <strong>rigor<\/strong> do <strong>calor<\/strong> causava mal-estar crescente at\u00e9 nos moradores de <strong>Salvador<\/strong><\/em>.<\/p>\n<p>Sem eco: O forte calor causava mal-estar crescente at\u00e9 nos moradores da capital baiana.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u00edngua encanta. Harmonias e ritmos seduzem ouvidos e arrebatam cora\u00e7\u00f5es. Como chegar l\u00e1? N\u00e3o h\u00e1 necessidade de m\u00e1gicas. Basta usar os recursos do c\u00f3digo \u2014 organizar as palavras de tal forma que a frase ganhe flu\u00eancia e ritmo. A melhor pista: ler o texto em voz alta. O que escapa aos olhos grita aos ouvidos. \u00c9 o caso do eco. A rima \u00e9 qualidade [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3708,221,2416,3709],"class_list":["post-20832","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-eco","tag-estilo","tag-harmonia","tag-rima"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=20832"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20832\/revisions"}],"predecessor-version":[{"id":20833,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20832\/revisions\/20833"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=20832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=20832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=20832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}