{"id":20228,"date":"2019-07-14T09:10:24","date_gmt":"2019-07-14T12:10:24","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=20228"},"modified":"2019-07-14T09:10:24","modified_gmt":"2019-07-14T12:10:24","slug":"millor-fernandes-alertou","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/millor-fernandes-alertou\/","title":{"rendered":"Mill\u00f4r Fernandes alertou"},"content":{"rendered":"<p>\u201c\u00c9 bom n\u00e3o esquecer que o inventor do alfabeto foi um analfabeto.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u00c9 bom n\u00e3o esquecer que o inventor do alfabeto foi um analfabeto.\u201d &nbsp; \u00a0<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[133,3470,41,1719],"class_list":["post-20228","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-alfabeto","tag-analfabeto","tag-citacao","tag-millor-fernandes"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=20228"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20228\/revisions"}],"predecessor-version":[{"id":20229,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20228\/revisions\/20229"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=20228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=20228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=20228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}