{"id":20194,"date":"2019-07-11T11:51:09","date_gmt":"2019-07-11T14:51:09","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=20194"},"modified":"2019-07-11T11:51:09","modified_gmt":"2019-07-11T14:51:09","slug":"ja-nao-respirava-mais-naooooooooo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/ja-nao-respirava-mais-naooooooooo\/","title":{"rendered":"J\u00e1 n\u00e3o respirava mais? N\u00e3ooooooooo"},"content":{"rendered":"<p>Nada de dose dupla. Nas indica\u00e7\u00f5es temporais, onde couber<strong> <em>j\u00e1<\/em><\/strong>, o <strong><em>mais<\/em><\/strong> n\u00e3o tem vez: <em>Quando o socorro chegou, o acidentado j\u00e1 n\u00e3o respirava<\/em> (n\u00e3o: j\u00e1 n\u00e3o respirava mais). <em>J\u00e1 n\u00e3o h\u00e1 leis que inibam as invas\u00f5es em Bras\u00edlia<\/em> (n\u00e3o: j\u00e1 n\u00e3o h\u00e1 mais leis). <em>Quando se divorciou, j\u00e1 n\u00e3o vivia com o marido<\/em> (n\u00e3o: j\u00e1 n\u00e3o vivia mais).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada de dose dupla. Nas indica\u00e7\u00f5es temporais, onde couber j\u00e1, o mais n\u00e3o tem vez: Quando o socorro chegou, o acidentado j\u00e1 n\u00e3o respirava (n\u00e3o: j\u00e1 n\u00e3o respirava mais). J\u00e1 n\u00e3o h\u00e1 leis que inibam as invas\u00f5es em Bras\u00edlia (n\u00e3o: j\u00e1 n\u00e3o h\u00e1 mais leis). Quando se divorciou, j\u00e1 n\u00e3o vivia com o marido (n\u00e3o: j\u00e1 n\u00e3o vivia mais).<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3465,2836],"class_list":["post-20194","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-ja","tag-mais"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=20194"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20194\/revisions"}],"predecessor-version":[{"id":20196,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/20194\/revisions\/20196"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=20194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=20194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=20194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}