{"id":19759,"date":"2019-05-26T09:01:53","date_gmt":"2019-05-26T12:01:53","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19759"},"modified":"2019-05-26T09:01:53","modified_gmt":"2019-05-26T12:01:53","slug":"nova-previdencia-eufemismo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/nova-previdencia-eufemismo\/","title":{"rendered":"Nova Previd\u00eancia: eufemismo"},"content":{"rendered":"<p>Era reforma da Previd\u00eancia. Virou Nova Previd\u00eancia. Por qu\u00ea? As palavras s\u00e3o m\u00e1gicas. Algumas chocam, causam dor ou provocam imagens desagrad\u00e1veis. A sa\u00edda? Apelar para outras, sem a carga da rejei\u00e7\u00e3o. A mudan\u00e7a nas regras da aposentadoria vem levando pancadas h\u00e1 mais de duas d\u00e9cadas. Este ano n\u00e3o foi diferente. Apanhava da direita, da esquerda, de cima e de baixo. O jeito? Convocar o eufemismo. Ao trocar seis por meia d\u00fazia, o governo ado\u00e7a o termo e, com isso, torna-o mais palat\u00e1vel.<\/p>\n<p><b>Vade retro<\/b><\/p>\n<p>H\u00e1 exemplos pra dar, vender e emprestar. Muitos n\u00e3o gostam de pronunciar a palavra morte. Sentem medo. O que fazem? O mesmo que Bolsonaro &amp; cia. Manuel Bandeira chamou-a de \u201ca indesejada das gentes\u201d. Outros dizem falecimento, viagem, ida desta pra melhor, mudar-se para a companhia do Senhor, espichar as canelas, vestir palet\u00f3 de madeira, bater as botas. E por a\u00ed vai.<\/p>\n<p><i>Diabo<\/i> n\u00e3o fica atr\u00e1s. A l\u00edngua oferece mil artimanhas para fugir do espertalh\u00e3o que, dizem, n\u00e3o \u00e9 perigoso por ser diabo, mas por ser velho, pra l\u00e1 de vivido. Eis recursos: demo, bicho, c\u00e3o, bei\u00e7udo, canhoto, coxo, anhang\u00e1, coisa ruim, anjo rebelde. Valha-nos, Deus! Vade retro, satan\u00e1s!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era reforma da Previd\u00eancia. Virou Nova Previd\u00eancia. Por qu\u00ea? As palavras s\u00e3o m\u00e1gicas. Algumas chocam, causam dor ou provocam imagens desagrad\u00e1veis. A sa\u00edda? Apelar para outras, sem a carga da rejei\u00e7\u00e3o. A mudan\u00e7a nas regras da aposentadoria vem levando pancadas h\u00e1 mais de duas d\u00e9cadas. Este ano n\u00e3o foi diferente. Apanhava da direita, da esquerda, de cima e de baixo. O jeito? Convocar o eufemismo. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[2462,3273,1933,2817,2772],"class_list":["post-19759","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-diabo","tag-enfemismo","tag-morte","tag-nova-previdencia","tag-reforma-da-previdencia"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19759"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19759\/revisions"}],"predecessor-version":[{"id":19760,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19759\/revisions\/19760"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}