{"id":19638,"date":"2019-05-12T07:18:58","date_gmt":"2019-05-12T10:18:58","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19638"},"modified":"2019-05-12T07:18:58","modified_gmt":"2019-05-12T10:18:58","slug":"mae-piada","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/mae-piada\/","title":{"rendered":"M\u00e3e: piada"},"content":{"rendered":"<p>O Dia das M\u00e3es chegava. A professora pediu uma reda\u00e7\u00e3o. Todas deveriam terminar com esta frase: \u201cM\u00e3e s\u00f3 tem uma\u201d. A meninada p\u00f4s m\u00e3os \u00e0 obra. Alguns contaram epis\u00f3dios da inf\u00e2ncia. Outros, cuidados em caso de doen\u00e7a. N\u00e3o faltou quem falasse em ajuda nos deveres de casa ou em sufocos devidos a confus\u00f5es inesperadas.<\/p>\n<p>Um deles contou hist\u00f3ria com enredo diferente. Uma visita havia chegado \u00e0 casa da fam\u00edlia. Alvoro\u00e7o geral. A m\u00e3e, sol\u00edcita, pediu ao filho que pegasse duas Cocas na geladeira. Depois de minutos, o garoto voltou:<\/p>\n<p>\u2014 M\u00e3e, s\u00f3 tem uma.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dia das M\u00e3es chegava. A professora pediu uma reda\u00e7\u00e3o. Todas deveriam terminar com esta frase: \u201cM\u00e3e s\u00f3 tem uma\u201d. A meninada p\u00f4s m\u00e3os \u00e0 obra. Alguns contaram epis\u00f3dios da inf\u00e2ncia. Outros, cuidados em caso de doen\u00e7a. N\u00e3o faltou quem falasse em ajuda nos deveres de casa ou em sufocos devidos a confus\u00f5es inesperadas. Um deles contou hist\u00f3ria com enredo diferente. Uma visita havia chegado [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3223,298],"class_list":["post-19638","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-mae-so-tem-uma","tag-piada"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19638"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19638\/revisions"}],"predecessor-version":[{"id":19639,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19638\/revisions\/19639"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}