{"id":19518,"date":"2019-04-28T11:17:18","date_gmt":"2019-04-28T14:17:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19518"},"modified":"2019-04-28T11:17:18","modified_gmt":"2019-04-28T14:17:18","slug":"cargos-e-funcoes-feminino","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cargos-e-funcoes-feminino\/","title":{"rendered":"Cargos e fun\u00e7\u00f5es: feminino"},"content":{"rendered":"<p>Cargos e fun\u00e7\u00f5es se flexionam em g\u00eanero? Sim. Se exercidos por mulher, escrevem-se no feminino. Presidente (ou presidenta), agente administrativa, secret\u00e1ria-executiva servem de exemplo. Aten\u00e7\u00e3o ao exagero. Siga a \u00edndole da l\u00edngua. Na concorr\u00eancia de feminino e masculino, fique com o masculino plural. Filhos engloba filhos e filhas. Brasileiros, brasileiros e brasileiras. Amigos, amigos e amigas. N\u00e3o caia no modismo irritante de discriminar \u2014 sem necessidade \u2014 o sexo das pessoas: os presentes e as presentes, os leitores e as leitoras, os embaixadores e as embaixadoras. Cruz-credo!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargos e fun\u00e7\u00f5es se flexionam em g\u00eanero? Sim. Se exercidos por mulher, escrevem-se no feminino. Presidente (ou presidenta), agente administrativa, secret\u00e1ria-executiva servem de exemplo. Aten\u00e7\u00e3o ao exagero. Siga a \u00edndole da l\u00edngua. Na concorr\u00eancia de feminino e masculino, fique com o masculino plural. Filhos engloba filhos e filhas. Brasileiros, brasileiros e brasileiras. Amigos, amigos e amigas. N\u00e3o caia no modismo irritante de discriminar \u2014 sem [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3166,248,144,2775],"class_list":["post-19518","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-cargos","tag-feminino","tag-flexao","tag-funcoes"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19518"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19518\/revisions"}],"predecessor-version":[{"id":19519,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19518\/revisions\/19519"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}