{"id":19348,"date":"2019-04-10T09:43:54","date_gmt":"2019-04-10T12:43:54","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19348"},"modified":"2019-04-10T09:43:54","modified_gmt":"2019-04-10T12:43:54","slug":"crase-a-capitao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/crase-a-capitao\/","title":{"rendered":"Crase: \u00e0 capit\u00e3o"},"content":{"rendered":"<p>Para<span class=\"im\"> as For\u00e7as Armadas, capit\u00e3o \u00e9 um substantivo comum de dois g\u00eaneros (apesar de haver<br \/>\no feminino capit\u00e3). Nos quart\u00e9is, ele \u00e9 o capit\u00e3o; ela, a capit\u00e3o. Trata-se<br \/>\nda cultura da institui\u00e7\u00e3o. Mas ela d\u00e1 n\u00f3 nos miolos nos miolos. Qual a<br \/>\nconstru\u00e7\u00e3o correta?<br \/>\na. Entrega de medalha \u00e0 capit\u00e3o-de-corveta Maria da Silva.<br \/>\nb. Entrega de medalha a capit\u00e3o-de-corveta Maria da Silva.<br \/>\n<\/span><span class=\"im\"><br \/>\nCrase \u00e9 como alian\u00e7a no anular esquerdo. Indica o casamento de dois aa. Um<br \/>\ndeles \u00e9 a preposi\u00e7\u00e3o. O outro, em geral, o artigo definido. Quando os dois<br \/>\n<\/span> se encontram, n\u00e3o d\u00e1 outra. \u00c9 enlace na certa: <em>Jurou fidelidade \u00e0 p\u00e1tria.<\/em><br \/>\n<em>Dirigiu-se \u00e0 poltrona indicada. Foi \u00e0 livraria Cultura pegar os livros<\/em>.<\/p>\n<p>Pintou a d\u00favida? Substitua a palavra feminina por uma masculina (n\u00e3o<br \/>\nprecisa ser sin\u00f4nima, mas tem de ser do mesmo n\u00famero \u2014 singular ou plural).<br \/>\nSe no troca-troca der <strong>ao<\/strong>, sinal de crase. Caso contr\u00e1rio, nada feito:<\/p>\n<p><em>Jurou fidelidade <strong>\u00e0<\/strong> p\u00e1tria. Jurou fidelidade <strong>ao<\/strong> pa\u00eds.<\/em><br \/>\n<em>Dirigiu-se <strong>\u00e0<\/strong> poltrona indicada. Dirigiu-se <strong>ao<\/strong> pa\u00eds indicado.<\/em><br \/>\n<em>Foi <strong>\u00e0<\/strong> livraria Cultura pegar os livros. Foi <strong>ao<\/strong> restaurante pegar os<\/em><br \/>\n<em>livros.<\/em><br \/>\n<em>Visitou <strong>a<\/strong> amiga no fim de semana. Visitou <strong>o<\/strong> amigo no fim de semana.<\/em><\/p>\n<p>Agora, fa\u00e7a a sua aposta: a capit\u00e3o ou \u00e0 capit\u00e3o? Antes de arriscar,<br \/>\nrecorra ao tira-teima:<\/p>\n<p>Entrega de medalha <strong>\u00e0<\/strong> capit\u00e3o-de-corveta Maria da Silva.<\/p>\n<p>Entrega de medalha <strong>ao<\/strong> capit\u00e3o-de-corveta Jo\u00e3o da Silva.<\/p>\n<p>\u00c9 isso. Com o truque, a alternativa \u00e9 acertar ou acertar. Viva!<\/p>\n<p><span class=\"im\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para as For\u00e7as Armadas, capit\u00e3o \u00e9 um substantivo comum de dois g\u00eaneros (apesar de haver o feminino capit\u00e3). Nos quart\u00e9is, ele \u00e9 o capit\u00e3o; ela, a capit\u00e3o. Trata-se da cultura da institui\u00e7\u00e3o. Mas ela d\u00e1 n\u00f3 nos miolos nos miolos. Qual a constru\u00e7\u00e3o correta? a. Entrega de medalha \u00e0 capit\u00e3o-de-corveta Maria da Silva. b. Entrega de medalha a capit\u00e3o-de-corveta Maria da Silva. Crase \u00e9 como [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[3079,166],"class_list":["post-19348","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-capitao","tag-crase"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19348"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19348\/revisions"}],"predecessor-version":[{"id":19353,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19348\/revisions\/19353"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}