{"id":19261,"date":"2019-04-02T12:14:10","date_gmt":"2019-04-02T15:14:10","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19261"},"modified":"2019-04-02T12:14:10","modified_gmt":"2019-04-02T15:14:10","slug":"e-um-barato-origem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/e-um-barato-origem\/","title":{"rendered":"\u00c9 um barato: origem"},"content":{"rendered":"<p>A origem de barato? S\u00f3 podia ser ela. A palavra vem da l\u00edngua do povo que mais sabe negociar no mundo. \u00c9 o \u00e1rabe. No idioma de Maom\u00e9 e de Cam\u00f5es, mant\u00e9m o significado: pre\u00e7o baixo. Ora, como o corpo \u00e9 a parte mais sens\u00edvel do corpo, o brasileiro lhe acrescentou um ingrediente. Diz \u201co maior barato\u201d. Eta coisa boa!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A origem de barato? S\u00f3 podia ser ela. A palavra vem da l\u00edngua do povo que mais sabe negociar no mundo. \u00c9 o \u00e1rabe. No idioma de Maom\u00e9 e de Cam\u00f5es, mant\u00e9m o significado: pre\u00e7o baixo. Ora, como o corpo \u00e9 a parte mais sens\u00edvel do corpo, o brasileiro lhe acrescentou um ingrediente. Diz \u201co maior barato\u201d. Eta coisa boa!<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1405,116,145,3035],"class_list":["post-19261","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-arabe","tag-barato","tag-etimologia","tag-o-maior-barato"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19261"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19261\/revisions"}],"predecessor-version":[{"id":19262,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19261\/revisions\/19262"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}