{"id":1923,"date":"2015-11-03T15:51:39","date_gmt":"2015-11-03T17:51:39","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=1923"},"modified":"2015-11-25T19:40:03","modified_gmt":"2015-11-25T21:40:03","slug":"erramos-162","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-162\/","title":{"rendered":"Erramos"},"content":{"rendered":"<p>\u201cSindicalistas dizem que o pessimismo do governador decorre dele n\u00e3o conhecer a realidade\u201d, escrevemos na p\u00e1g. 9. Ops! Desrespeitamos o sujeito. Ele nunca, nunca mesmo, \u00e9 preposicionado. Melhor: Sindicalistas dizem que o pessimismo do governador decorre de ele n\u00e3o conhecer a realidade .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSindicalistas dizem que o pessimismo do governador decorre dele n\u00e3o conhecer a realidade\u201d, escrevemos na p\u00e1g. 9. Ops! Desrespeitamos o sujeito. Ele nunca, nunca mesmo, \u00e9 preposicionado. Melhor: Sindicalistas dizem que o pessimismo do governador decorre de ele n\u00e3o conhecer a realidade .<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1923","post","type-post","status-publish","format-standard","hentry","category-erramos"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/1923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=1923"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/1923\/revisions"}],"predecessor-version":[{"id":1925,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/1923\/revisions\/1925"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=1923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=1923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=1923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}