{"id":19201,"date":"2019-03-28T13:15:01","date_gmt":"2019-03-28T16:15:01","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19201"},"modified":"2019-03-28T13:15:01","modified_gmt":"2019-03-28T16:15:01","slug":"max-gehringer-pergunta-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/max-gehringer-pergunta-2\/","title":{"rendered":"Max Gehringer pergunta"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>\u201cPor que as pessoas ficam inventando express\u00f5es estranhas ou usando palavras estrangeiras quando \u00e9 muito mais f\u00e1cil falar portugu\u00eas?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u201cPor que as pessoas ficam inventando express\u00f5es estranhas ou usando palavras estrangeiras quando \u00e9 muito mais f\u00e1cil falar portugu\u00eas? &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[41,2997,2745],"class_list":["post-19201","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-citacao","tag-estrangeirinhos","tag-max-gehringer"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19201"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19201\/revisions"}],"predecessor-version":[{"id":19202,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19201\/revisions\/19202"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}