{"id":19101,"date":"2019-03-11T11:20:18","date_gmt":"2019-03-11T14:20:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19101"},"modified":"2019-03-11T11:20:18","modified_gmt":"2019-03-11T14:20:18","slug":"cujo-emprego-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/cujo-emprego-3\/","title":{"rendered":"Cujo: emprego"},"content":{"rendered":"<p>Quer pronome sofisticado? Fique com o <em>cujo. P<\/em>ouca gente o emprega. Inseguran\u00e7a talvez.<\/p>\n<p>N\u00e3o\u00a0 \u00e9\u00a0para menos. O <em>cujo<\/em> tem suas manhas. S\u00e3o tr\u00eas:<\/p>\n<p><strong>1<\/strong>. Separa\u00e7\u00e3o sil\u00e1bica. No fim da linha, forma palavr\u00e3o. Deus nos acuda. \u00c9 igual a federal. Todo o cuidado com eles \u00e9 pouco.<\/p>\n<p><strong>\u00a02<\/strong>. O emprego<\/p>\n<p>O cujo tem uma miss\u00e3o muito especial: juntar duas frases para evitar repeti\u00e7\u00e3o de palavras. Com uma particularidade \u2013 <strong>sempre indica posse<\/strong>.<\/p>\n<ul>\n<li><em> O ministro foi indelicado com a deputada. O candidato <strong>do ministro<\/strong> <\/em>(= <em>candidato dele) perdeu a elei\u00e7\u00e3o. <\/em><\/li>\n<\/ul>\n<p><em>O ministro cujo candidato perdeu a elei\u00e7\u00e3o foi indelicado com a deputada. <\/em><\/p>\n<ul>\n<li><em>\u00a0 Joana est\u00e1 feliz com a visita da cegonha. Os<\/em> <em>filhos <strong>de Joana<\/strong> nasceram h\u00e1 uma semana. <\/em><\/li>\n<\/ul>\n<p>Joana<em>, cujos filhos nasceram h\u00e1\u00a0uma semana, est\u00e1\u00a0 feliz com a visita da cegonha. <\/em><\/p>\n<ul>\n<li>O <em>livro esgotou-se em tr\u00eas dias. O<\/em> <em>autor <strong>do livro<\/strong> foi premiado na Fran\u00e7a. <\/em><\/li>\n<\/ul>\n<p>O <em>livro cujo autor foi premiado na Fran\u00e7a esgotou-se em tr\u00eas dias. <\/em><\/p>\n<ul>\n<li>O <em>candidato venceu a elei\u00e7\u00e3o em primeiro turno. N\u00e3o pude atender os pedidos <strong>do candidato<\/strong>. <\/em><\/li>\n<\/ul>\n<p>O <em>candidato cujos pedidos n\u00e3o pude atender venceu a elei\u00e7\u00e3o em primeiro turno. <\/em><\/p>\n<p><strong>3<\/strong>. Rejei\u00e7\u00e3o ao artigo<\/p>\n<p>O cujo rejeita o artigo. Nunca diga, por exemplo: Carlos, cujo o candidato foi o mais votado no centro acad\u00eamico, quer disputar uma vaga na C\u00e2mara. Nunca mesmo. Pega mal como palitar os dentes em p\u00fablico. Fa\u00e7a bonito. Assim: Carlos, cujo candidato foi o mais votado no centro acad\u00eamico, quer disputar uma vaga na C\u00e2mara.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer pronome sofisticado? Fique com o cujo. Pouca gente o emprega. Inseguran\u00e7a talvez. N\u00e3o\u00a0 \u00e9\u00a0para menos. O cujo tem suas manhas. S\u00e3o tr\u00eas: 1. Separa\u00e7\u00e3o sil\u00e1bica. No fim da linha, forma palavr\u00e3o. Deus nos acuda. \u00c9 igual a federal. Todo o cuidado com eles \u00e9 pouco. \u00a02. O emprego O cujo tem uma miss\u00e3o muito especial: juntar duas frases para evitar repeti\u00e7\u00e3o de palavras. Com [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[136,1568,1569,1567,2936],"class_list":["post-19101","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-artigo","tag-cujo","tag-posse","tag-pronome-relativo","tag-separacao-silabica"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19101"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19101\/revisions"}],"predecessor-version":[{"id":19102,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19101\/revisions\/19102"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}