{"id":19095,"date":"2019-03-11T11:02:20","date_gmt":"2019-03-11T14:02:20","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19095"},"modified":"2019-03-11T11:02:20","modified_gmt":"2019-03-11T14:02:20","slug":"a-principio-x-em-principio-quando-usar","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a-principio-x-em-principio-quando-usar\/","title":{"rendered":"A princ\u00edpio x em princ\u00edpio: quando usar"},"content":{"rendered":"<p>Parecido n\u00e3o\u00a0\u00e9\u00a0igual. Mas confunde. Com o substantivo <em>princ\u00edpio<\/em>, a preposi\u00e7\u00e3o faz a diferen\u00e7a.<\/p>\n<p><strong>\u00a0Em princ\u00edpio<\/strong> significa antes de mais nada, antes de qualquer considera\u00e7\u00e3o, teoricamente, em tese, de modo geral:<\/p>\n<ul>\n<li><em> Em princ\u00edpio, toda mudan\u00e7a \u00e9 ben\u00e9fica. <\/em><\/li>\n<li><em> Estamos, em princ\u00edpio, abertos \u00e0s novidades tecnol\u00f3gicas. <\/em><\/li>\n<\/ul>\n<p><strong>\u00a0A princ\u00edpio<\/strong> quer dizer no come\u00e7o, inicialmente:<\/p>\n<ul>\n<li><em> A princ\u00edpio o Brasil era o favorito das apostas. Depois da partida de estreia, deixou de s\u00ea-lo. <\/em><\/li>\n<li><em> Toda conquista \u00e9, a princ\u00edpio, muito excitante. Com o tempo, pode mudar de figura. <\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Parecido n\u00e3o\u00a0\u00e9\u00a0igual. Mas confunde. Com o substantivo princ\u00edpio, a preposi\u00e7\u00e3o faz a diferen\u00e7a. \u00a0Em princ\u00edpio significa antes de mais nada, antes de qualquer considera\u00e7\u00e3o, teoricamente, em tese, de modo geral: Em princ\u00edpio, toda mudan\u00e7a \u00e9 ben\u00e9fica. Estamos, em princ\u00edpio, abertos \u00e0s novidades tecnol\u00f3gicas. \u00a0A princ\u00edpio quer dizer no come\u00e7o, inicialmente: A princ\u00edpio o Brasil era o favorito das apostas. Depois da partida de estreia, deixou [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1077,1078],"class_list":["post-19095","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-a-principio","tag-em-principio"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19095"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19095\/revisions"}],"predecessor-version":[{"id":19096,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19095\/revisions\/19096"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}