{"id":19085,"date":"2019-03-11T08:59:37","date_gmt":"2019-03-11T11:59:37","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=19085"},"modified":"2019-03-11T09:00:38","modified_gmt":"2019-03-11T12:00:38","slug":"grafia-x-e-cha","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/grafia-x-e-cha\/","title":{"rendered":"Grafia: x e ch"},"content":{"rendered":"<p>Chove de norte a sul do Brasil. S\u00e3o as \u00e1guas de mar\u00e7o despedindo o ver\u00e3o. Mas S\u00e3o Paulo est\u00e1 sendo especialmente castigada. Alagamentos, enxurradas, enchentes, queda de \u00e1rvores e perda de vidas s\u00e3o constantes no quadro dram\u00e1tico. A rep\u00f3rter C\u00edntia Cardoso escrevia sobre o assunto. Ficou curiosa ao observar duas palavras \u2014 enxurrada e enchente. Por que uma se grafa com x e a outra com ch?<\/p>\n<p>C\u00edntia, trata-se de uma das poucas regras de grafia. Depois de <b>en<\/b>, d\u00ea passagem ao x. Assim: <i>enxoval, enxame, enxada, enxergar, enxaqueca, enxaguar, enxerto, enxugar, enxofre, enxurrada<\/i>.<\/p>\n<p>H\u00e1 exce\u00e7\u00f5es? N\u00e3o. O que existe \u00e9 regra que fica acima de todas as outras. Ei-la: a fam\u00edlia acima de tudo. Diante dela, cessa tudo o que a musa antiga canta. A palavra derivada mant\u00e9m-se fiel \u00e0 primitiva \u2014 sem choro nem vela: <i>cheio (encher, enchente), charco (encharcado), chap\u00e9u (enchapelar), chocalho (enchocalhar).<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chove de norte a sul do Brasil. S\u00e3o as \u00e1guas de mar\u00e7o despedindo o ver\u00e3o. Mas S\u00e3o Paulo est\u00e1 sendo especialmente castigada. Alagamentos, enxurradas, enchentes, queda de \u00e1rvores e perda de vidas s\u00e3o constantes no quadro dram\u00e1tico. A rep\u00f3rter C\u00edntia Cardoso escrevia sobre o assunto. Ficou curiosa ao observar duas palavras \u2014 enxurrada e enchente. Por que uma se grafa com x e a outra [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[273,1862,1857,70,272],"class_list":["post-19085","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-ch","tag-enchente","tag-enxurrada","tag-grafia","tag-x"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=19085"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19085\/revisions"}],"predecessor-version":[{"id":19090,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/19085\/revisions\/19090"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=19085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=19085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=19085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}