{"id":18565,"date":"2019-01-23T17:16:42","date_gmt":"2019-01-23T19:16:42","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=18565"},"modified":"2019-01-23T17:16:42","modified_gmt":"2019-01-23T19:16:42","slug":"propriedade-vocabular-temperatura","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/propriedade-vocabular-temperatura\/","title":{"rendered":"Propriedade vocabular: temperatura"},"content":{"rendered":"<p>Que calor! Bras\u00edlia parece um forno. Boa parte do Brasil tamb\u00e9m. Da\u00ed por que entraram em cartaz quatro adjetivos \u2014 quente, frio, alto, baixo. Aten\u00e7\u00e3o para a propriedade vocabular. Frio e quente usam-se para tempo (tempo quente, tempo frio, dia quente, dia frio, tarde quente, tarde fria). A temperatura n\u00e3o pode ser quente nem fria. \u00c9 alta ou baixa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que calor! Bras\u00edlia parece um forno. Boa parte do Brasil tamb\u00e9m. Da\u00ed por que entraram em cartaz quatro adjetivos \u2014 quente, frio, alto, baixo. Aten\u00e7\u00e3o para a propriedade vocabular. Frio e quente usam-se para tempo (tempo quente, tempo frio, dia quente, dia frio, tarde quente, tarde fria). A temperatura n\u00e3o pode ser quente nem fria. \u00c9 alta ou baixa.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1459,1460,1458,114,1457,2540,35],"class_list":["post-18565","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-alta","tag-baixa","tag-frio","tag-propriedade-vocabular","tag-quente","tag-temperatura","tag-tempo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=18565"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18565\/revisions"}],"predecessor-version":[{"id":18566,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18565\/revisions\/18566"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=18565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=18565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=18565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}