{"id":18332,"date":"2019-01-06T10:29:53","date_gmt":"2019-01-06T12:29:53","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=18332"},"modified":"2019-01-06T10:29:53","modified_gmt":"2019-01-06T12:29:53","slug":"grafia-das-letras-adeus-duvidas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/grafia-das-letras-adeus-duvidas\/","title":{"rendered":"Grafia das letras: adeus, d\u00favidas"},"content":{"rendered":"<p>Viva! Com a reforma ortogr\u00e1fica, nosso alfabeto ganhou tr\u00eas letras. K, y e w o deixaram mais rico. Mas a grafia das 26 senhoritas n\u00e3o mudou. Apesar da perman\u00eancia, muitos trope\u00e7am na escrita da primeirona da lista. Sabe por qu\u00ea? Por causa do acento. O \u00e1 se escreve assim \u2013 com o grampinho agudo: <em>As crian\u00e7as come\u00e7am a alfabetiza\u00e7\u00e3o pelo \u00e1-b\u00ea-c\u00ea.<\/em><\/p>\n<p><strong>Outra cara<\/strong><\/p>\n<p>\u00c1-b\u00ea-c\u00ea pode ter outra cara. \u00c9 abc. Uma e outra d\u00e3o o mesmo recado. Trata-se do alfabeto.<\/p>\n<p><strong>Desfile <\/strong><\/p>\n<p>Como se escrevem as 26 letras? Deste jeitinho: \u00e1, b\u00ea, c\u00ea, d\u00ea, e, efe, g\u00ea, ag\u00e1, i, jota, k\u00e1, ele, eme, ene, o, p\u00ea, qu\u00ea, erre, esse, t\u00ea, u, v\u00ea xis, d\u00e1blio, \u00edpsilon, z\u00ea.<\/p>\n<p><strong>\u00c9 assim<\/strong><\/p>\n<p>Letras, como boas filhas de Deus, t\u00eam plural. Ele pode ser expresso de duas maneiras. Uma: com dose dupla: os aa, os bb, os cc, os dd, os yy, os zz. A outra: com o acr\u00e9scimo do s: os \u00e1s, os b\u00eas, os c\u00eas, os d\u00eas, os efes, os z\u00eas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viva! Com a reforma ortogr\u00e1fica, nosso alfabeto ganhou tr\u00eas letras. K, y e w o deixaram mais rico. Mas a grafia das 26 senhoritas n\u00e3o mudou. Apesar da perman\u00eancia, muitos trope\u00e7am na escrita da primeirona da lista. Sabe por qu\u00ea? Por causa do acento. O \u00e1 se escreve assim \u2013 com o grampinho agudo: As crian\u00e7as come\u00e7am a alfabetiza\u00e7\u00e3o pelo \u00e1-b\u00ea-c\u00ea. Outra cara \u00c1-b\u00ea-c\u00ea pode [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[294,133,70,134,135],"class_list":["post-18332","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-acento","tag-alfabeto","tag-grafia","tag-letras","tag-plural"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=18332"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18332\/revisions"}],"predecessor-version":[{"id":18333,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18332\/revisions\/18333"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=18332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=18332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=18332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}