{"id":18252,"date":"2018-12-30T20:40:00","date_gmt":"2018-12-30T22:40:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=18252"},"modified":"2018-12-30T20:40:00","modified_gmt":"2018-12-30T22:40:00","slug":"maiusculas-e-minusculas-meses","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/maiusculas-e-minusculas-meses\/","title":{"rendered":"Mai\u00fasculas e min\u00fasculas: meses"},"content":{"rendered":"<h3>Olho vivo, marinheiro de poucas viagens. Eles s\u00e3o 12. Repetem-se ano ap\u00f3s ano. Uns t\u00eam 30 dias. Outros, 31. S\u00f3 um se conforma com 28. De quatro em quatro anos, ganha um de presente. Fica com 29. Apesar das diferen\u00e7as de tamanho, os meses t\u00eam um denominador comum. Escrevem-se com a letra inicial mixuruuuuuuuuuuuuuca: <em>janeiro, fevereiro, mar\u00e7o, abril, maio.<\/em><\/h3>\n<h3><strong>Vira-vira<\/strong><\/h3>\n<h3>As palavras s\u00e3o vira-casacas. Mudam de classe como mudamos de camiseta. Vale o exemplo do substantivo. Nome pr\u00f3prio vira comum sem cerim\u00f4nia. \u00c9 o caso de Jo\u00e3o, Maria, Par\u00e1, Brasil. Eles perdem o pedigree em jo\u00e3o-de-barro, banho-maria, castanha-do-par\u00e1, pau-brasil. Nome comum tamb\u00e9m vira pr\u00f3prio. O m\u00eas, em datas comemorativas, ganha nobreza. Grafa-se com a inicial grandoooooooooona: o 7 de Setembro, o 1\u00ba de Maio.<\/h3>\n<h3><strong>\u00a0<\/strong><\/h3>\n<h3><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Olho vivo, marinheiro de poucas viagens. Eles s\u00e3o 12. Repetem-se ano ap\u00f3s ano. Uns t\u00eam 30 dias. Outros, 31. S\u00f3 um se conforma com 28. De quatro em quatro anos, ganha um de presente. Fica com 29. Apesar das diferen\u00e7as de tamanho, os meses t\u00eam um denominador comum. Escrevem-se com a letra inicial mixuruuuuuuuuuuuuuca: janeiro, fevereiro, mar\u00e7o, abril, maio. Vira-vira As palavras s\u00e3o vira-casacas. Mudam [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[2342,70,181,1330,182],"class_list":["post-18252","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-datas-comemorativas","tag-grafia","tag-maiusculas","tag-meses","tag-minusculas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=18252"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18252\/revisions"}],"predecessor-version":[{"id":18255,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/18252\/revisions\/18255"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=18252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=18252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=18252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}