{"id":17879,"date":"2018-11-22T16:37:46","date_gmt":"2018-11-22T18:37:46","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=17879"},"modified":"2018-11-22T16:37:46","modified_gmt":"2018-11-22T18:37:46","slug":"dado-concordancia","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dado-concordancia\/","title":{"rendered":"Dado: concord\u00e2ncia"},"content":{"rendered":"<p><strong>Dado<\/strong> concorda com o substantivo em g\u00eanero e n\u00famero:<\/p>\n<p><em>Dado o exposto, sugiro seja efetuado o pagamento.<\/em><\/p>\n<p><em>Dados os antecedentes, imp\u00f5em-se investiga\u00e7\u00f5es mais s\u00e9rias.<\/em><\/p>\n<p><em>Dada a circunst\u00e2ncia, ela dificilmente chegar\u00e1 a tempo.<br \/>\n<\/em><\/p>\n<p><em>Dadas as circunst\u00e2ncias, \u00e9 melhor cancelar a viagem.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dado concorda com o substantivo em g\u00eanero e n\u00famero: Dado o exposto, sugiro seja efetuado o pagamento. Dados os antecedentes, imp\u00f5em-se investiga\u00e7\u00f5es mais s\u00e9rias. Dada a circunst\u00e2ncia, ela dificilmente chegar\u00e1 a tempo. Dadas as circunst\u00e2ncias, \u00e9 melhor cancelar a viagem. &nbsp; &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[235,2076,2078,2075,2077],"class_list":["post-17879","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-concordancia","tag-dada","tag-dadas","tag-dado","tag-dados"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=17879"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17879\/revisions"}],"predecessor-version":[{"id":17880,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17879\/revisions\/17880"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=17879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=17879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=17879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}