{"id":17745,"date":"2018-11-08T13:17:16","date_gmt":"2018-11-08T15:17:16","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=17745"},"modified":"2018-11-08T13:17:16","modified_gmt":"2018-11-08T15:17:16","slug":"caber-conjugacao-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/caber-conjugacao-3\/","title":{"rendered":"Caber: conjuga\u00e7\u00e3o"},"content":{"rendered":"<p>Cuidado com a conjuga\u00e7\u00e3o do verbo caber: caibo, cabe, cabemos, cabem; coube, coube, coubemos, couberam; cabia, cabia, cab\u00edamos, cabiam; caiba, caiba, caibamos, caibais; coubesse, coubesse, coub\u00e9ssemos, coubessem; couber, couber, coubermos, couberem; cabendo; cabido. <em>N\u00e3o caibo em mim de contente. E voc\u00ea? Espero que caiba.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuidado com a conjuga\u00e7\u00e3o do verbo caber: caibo, cabe, cabemos, cabem; coube, coube, coubemos, couberam; cabia, cabia, cab\u00edamos, cabiam; caiba, caiba, caibamos, caibais; coubesse, coubesse, coub\u00e9ssemos, coubessem; couber, couber, coubermos, couberem; cabendo; cabido. N\u00e3o caibo em mim de contente. E voc\u00ea? Espero que caiba. &nbsp; &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1586,124,123],"class_list":["post-17745","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-caber","tag-conjugacao","tag-verbo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=17745"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17745\/revisions"}],"predecessor-version":[{"id":17746,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17745\/revisions\/17746"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=17745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=17745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=17745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}