{"id":17498,"date":"2018-10-16T13:38:47","date_gmt":"2018-10-16T16:38:47","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=17498"},"modified":"2018-10-16T13:38:47","modified_gmt":"2018-10-16T16:38:47","slug":"concordancia-partitivo-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/concordancia-partitivo-2\/","title":{"rendered":"Concord\u00e2ncia: partitivo"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><span style=\"font-size: small\">A maioria dos estudantes saiu? Sa\u00edram? Ops! Trata-se de caso de concord\u00e2ncia pra l\u00e1 de sofisticado. \u00c9 o partitivo. Existem as express\u00f5es partitivas: <\/span><span style=\"font-size: small\"><i>parte de, uma por\u00e7\u00e3o de, o resto de, a metade de, a maioria de. <\/i>Quando elas s\u00e3o seguidas de substantivo ou pronome no plural \u2013 e s\u00f3 assim \u2013 o verbo se esbalda. Pode ir para o singular. Ou plural: <\/span><\/p>\n<p class=\"western\"><span style=\"font-size: small\"><i>A maioria dos estudantes saiu <\/i><\/span><span style=\"font-size: small\">(o verbo concorda com maioria). <\/span><\/p>\n<p class=\"western\"><span style=\"font-size: small\"><i>A maioria dos estudantes sa\u00edram <\/i><\/span><span style=\"font-size: small\">(concorda com estudantes). <\/span><\/p>\n<p class=\"western\"><span style=\"font-size: small\"><i>Metade das laranjas apodreceu <\/i><\/span><span style=\"font-size: small\">(concorda com metade). <\/span><\/p>\n<p class=\"western\"><span style=\"font-size: small\"><i>Metade das laranjas apodreceram <\/i><\/span><span style=\"font-size: small\">(concorda com laranjas). <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Pouco mais da metade das obras est\u00e1 pronta. <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Pouco mais da metade das obras est\u00e3o prontas. <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Mais de 66% do trabalho foi cancelado. <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Mais de 66% do trabalho foram cancelados. <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Boa parte dos alunos fizeram a reda\u00e7\u00e3o do Enem. <\/span><\/p>\n<p><span style=\"font-family: Arial, serif\">Boa parte dos alunos do Enem fez a reda\u00e7\u00e3o. <\/span><\/p>\n<p><strong><span style=\"font-family: Arial, serif\">Olho vivo<\/span><\/strong><\/p>\n<p><span style=\"font-family: Arial, serif\">A maioria da popula\u00e7\u00e3o votou nas elei\u00e7\u00f5es. (Ops! Sujeito e complemento t\u00eam o mesmo n\u00famero. Resultado: \u00c9 singular ou singular.) <\/span><\/p>\n<p>A maioria votou. (O partitivo n\u00e3o tem complemento. O verbo s\u00f3 pode concordar com maioria.)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A maioria dos estudantes saiu? Sa\u00edram? Ops! Trata-se de caso de concord\u00e2ncia pra l\u00e1 de sofisticado. \u00c9 o partitivo. Existem as express\u00f5es partitivas: parte de, uma por\u00e7\u00e3o de, o resto de, a metade de, a maioria de. Quando elas s\u00e3o seguidas de substantivo ou pronome no plural \u2013 e s\u00f3 assim \u2013 o verbo se esbalda. Pode ir para o singular. Ou plural: A maioria [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1804,1683,235,1682,1679,307],"class_list":["post-17498","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-a-maior-parte-de","tag-a-maioria-de","tag-concordancia","tag-metade-de","tag-partitivo","tag-percentagem"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=17498"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17498\/revisions"}],"predecessor-version":[{"id":17505,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/17498\/revisions\/17505"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=17498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=17498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=17498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}