{"id":16996,"date":"2018-08-27T08:51:28","date_gmt":"2018-08-27T11:51:28","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16996"},"modified":"2018-08-27T08:52:19","modified_gmt":"2018-08-27T11:52:19","slug":"chamado-modismo-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/chamado-modismo-2\/","title":{"rendered":"Chamado: modismo"},"content":{"rendered":"<p>Cuidado com o modismo. Use <em>chamado<\/em> s\u00f3 quando voc\u00ea falar de algo cujo nome n\u00e3o \u00e9 o referido, mas \u00e9 conhecido como tal. N\u00e3o h\u00e1 por que escrever, por exemplo, os &#8220;chamados exames preventivos&#8221;. Exame preventivo \u00e9 exame preventivo. O cinema n\u00e3o \u00e9 a \u201cchamada\u201d s\u00e9tima arte. \u00c9 a s\u00e9tima arte. As pra\u00e7as onde se re\u00fanem os drogados n\u00e3o \u00e9 a \u201cchamada\u201d cracol\u00e2ndia. \u00c9 a cracol\u00e2ndia. As ONGs n\u00e3o s\u00e3o o \u201cchamado\u201d terceiro setor. S\u00e3o o terceiro setor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuidado com o modismo. Use chamado s\u00f3 quando voc\u00ea falar de algo cujo nome n\u00e3o \u00e9 o referido, mas \u00e9 conhecido como tal. N\u00e3o h\u00e1 por que escrever, por exemplo, os &#8220;chamados exames preventivos&#8221;. Exame preventivo \u00e9 exame preventivo. O cinema n\u00e3o \u00e9 a \u201cchamada\u201d s\u00e9tima arte. \u00c9 a s\u00e9tima arte. As pra\u00e7as onde se re\u00fanem os drogados n\u00e3o \u00e9 a \u201cchamada\u201d cracol\u00e2ndia. \u00c9 a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1264,451],"class_list":["post-16996","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-chamado","tag-modismo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16996"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16996\/revisions"}],"predecessor-version":[{"id":16998,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16996\/revisions\/16998"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}