{"id":16781,"date":"2018-08-12T07:50:06","date_gmt":"2018-08-12T10:50:06","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16781"},"modified":"2018-08-12T07:50:06","modified_gmt":"2018-08-12T10:50:06","slug":"dia-dos-pais-origem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/dia-dos-pais-origem\/","title":{"rendered":"Dia dos Pais: origem"},"content":{"rendered":"<p>Viva! Hoje \u00e9 o Dia dos Pais. Todos os dias deveriam ser dedicados a ele. Talvez sejam. Mas o calend\u00e1rio escolheu o segundo domingo de agosto. Por qu\u00ea? A hist\u00f3ria vem de longe. Dizem que a homenagem nasceu na Babil\u00f4nia. Mas, modernamente, veio \u00e0 luz nos Estados Unidos em 1909.<\/p>\n<p>Sonora Louise Dodd criou a data para provar que se orgulhava do pai. John Bruce Dodd perdeu a mulher em 1898. Cuidou, sozinho, dos seis filhos. A menina escolheu o dia do anivers\u00e1rio dele, 19 de junho, para a comemora\u00e7\u00e3o. A iniciativa ganhou apoio. Em 1966, o ent\u00e3o presidente Lyndon Johnson bateu o martelo. Oficializou o terceiro domingo de junho como Dia dos Pais nos States.<\/p>\n<p><strong>No Brasil<\/strong><\/p>\n<p>Aqui, paizinhos e paiz\u00f5es ganharam seu dia em 1953. A primeira festa foi em 14 de agosto. A escolha n\u00e3o se deve ao acaso. Coincide com o anivers\u00e1rio de S\u00e3o Joaquim, pai de Maria e av\u00f4 de Jesus. Depois a data foi transferida para o segundo domingo de agosto. Por qu\u00ea? Por tr\u00eas raz\u00f5es. Uma: fica mais f\u00e1cil de lembrar. Outra: a maioria das pessoas n\u00e3o trabalha. A \u00faltima: o com\u00e9rcio, claro, fatura mais.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viva! Hoje \u00e9 o Dia dos Pais. Todos os dias deveriam ser dedicados a ele. Talvez sejam. Mas o calend\u00e1rio escolheu o segundo domingo de agosto. Por qu\u00ea? A hist\u00f3ria vem de longe. Dizem que a homenagem nasceu na Babil\u00f4nia. Mas, modernamente, veio \u00e0 luz nos Estados Unidos em 1909. Sonora Louise Dodd criou a data para provar que se orgulhava do pai. John Bruce [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[1016,1013,992,1012,1015,1014],"class_list":["post-16781","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-brasil","tag-data","tag-dia-dos-pais","tag-estados-unidos","tag-john-bruce-dodd","tag-sonora-dodd"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16781"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16781\/revisions"}],"predecessor-version":[{"id":16782,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16781\/revisions\/16782"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}