{"id":16710,"date":"2018-08-07T17:04:24","date_gmt":"2018-08-07T20:04:24","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16710"},"modified":"2018-08-07T17:04:24","modified_gmt":"2018-08-07T20:04:24","slug":"embora-emprego","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/embora-emprego\/","title":{"rendered":"Embora: emprego"},"content":{"rendered":"<p>A conjun\u00e7\u00e3o <em>embora<\/em> rejeita o ger\u00fandio. Mas, com frequ\u00eancia, aparece a dupla <em>embora sendo<\/em>. Nada feito. O <em>embora<\/em> tem um \u00fanico e eterno amor. \u00c9 o subjuntivo. O indicativo e o ger\u00fandio tentam tirar uma casquinha. Bobeiam. N\u00e3o t\u00eam vez: <em>Fuma embora seja atleta. Trabalhava muito embora ganhasse pouco. Embora tenha tirado boas notas, n\u00e3o conseguiu a vaga. <\/em><\/p>\n<p>Reparou? Quando vem antes da ora\u00e7\u00e3o principal, a ora\u00e7\u00e3o iniciada por <em>embora <\/em>pede v\u00edrgula. Quando vem depois, esnoba o sinalzinho. Manda-o plantar batata no asfalto. X\u00f4!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A conjun\u00e7\u00e3o embora rejeita o ger\u00fandio. Mas, com frequ\u00eancia, aparece a dupla embora sendo. Nada feito. O embora tem um \u00fanico e eterno amor. \u00c9 o subjuntivo. O indicativo e o ger\u00fandio tentam tirar uma casquinha. Bobeiam. N\u00e3o t\u00eam vez: Fuma embora seja atleta. Trabalhava muito embora ganhasse pouco. Embora tenha tirado boas notas, n\u00e3o conseguiu a vaga. Reparou? Quando vem antes da ora\u00e7\u00e3o principal, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[225,923,925,924,926,122,123],"class_list":["post-16710","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-conjuncao","tag-embora","tag-embora-sendo","tag-gerundio","tag-indicativo","tag-subjuntivo","tag-verbo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16710"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16710\/revisions"}],"predecessor-version":[{"id":16711,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16710\/revisions\/16711"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}