{"id":16632,"date":"2018-07-31T12:18:11","date_gmt":"2018-07-31T15:18:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16632"},"modified":"2018-07-31T12:23:58","modified_gmt":"2018-07-31T15:23:58","slug":"arguir-conjugacao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/arguir-conjugacao\/","title":{"rendered":"Arguir: conjuga\u00e7\u00e3o"},"content":{"rendered":"<p>Modo indicativo: presente (eu arguo, tu arguis, ele argui, n\u00f3s argu\u00edmos, v\u00f3s agu\u00eds, eles arguem); pret\u00e9rito perfeito (argu\u00ed, argu\u00edste, arguiu, arguimos, argu\u00edstes, argu\u00edram); pret\u00e9rito imperfeito (argu\u00eda, argu\u00edas, argu\u00eda, argu\u00edamos, argu\u00edeis, argu\u00edam); mais que perfeito (argu\u00edra, argu\u00edras, argu\u00edra, etc.); futuro do presente (arguirei, arguir\u00e1s, arguir\u00e1, arguiremos, arguireis, arguir\u00e3o). Futuro do pret\u00e9rito (arguiria, arguirias, arguiria, etc.).<\/p>\n<p>Modo subjuntivo: presente (argua, arguas, argua, arguamos, arguais, arguam); imperfeito (argu\u00edsse, argu\u00edsses, argu\u00edsse, argu\u00edssemos, argu\u00edssem.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modo indicativo: presente (eu arguo, tu arguis, ele argui, n\u00f3s argu\u00edmos, v\u00f3s agu\u00eds, eles arguem); pret\u00e9rito perfeito (argu\u00ed, argu\u00edste, arguiu, arguimos, argu\u00edstes, argu\u00edram); pret\u00e9rito imperfeito (argu\u00eda, argu\u00edas, argu\u00eda, argu\u00edamos, argu\u00edeis, argu\u00edam); mais que perfeito (argu\u00edra, argu\u00edras, argu\u00edra, etc.); futuro do presente (arguirei, arguir\u00e1s, arguir\u00e1, arguiremos, arguireis, arguir\u00e3o). Futuro do pret\u00e9rito (arguiria, arguirias, arguiria, etc.). Modo subjuntivo: presente (argua, arguas, argua, arguamos, arguais, arguam); imperfeito (argu\u00edsse, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[826,124,123],"class_list":["post-16632","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-arguir","tag-conjugacao","tag-verbo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16632"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16632\/revisions"}],"predecessor-version":[{"id":16635,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16632\/revisions\/16635"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}