{"id":16627,"date":"2018-07-31T07:30:40","date_gmt":"2018-07-31T10:30:40","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16627"},"modified":"2018-07-31T07:32:01","modified_gmt":"2018-07-31T10:32:01","slug":"o-mato","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/o-mato\/","title":{"rendered":"Mato Grosso? O Mato Grosso?"},"content":{"rendered":"<p>&#8220;Voc\u00ea vai no Mato Grosso, 60% do territ\u00f3rio est\u00e1 preservado&#8221;, disse \u00c1lvaro Dias na GloboNews. Trope\u00e7ou. Mato Grosso, Mato Grosso do Sul, Goi\u00e1s, Sergipe &amp; cia. dispensam o artigo: <em>Sou de Mato Grosso. Chegamos a Mato Grosso. Gosto de Mato Grosso do Sul. Voc\u00ea mora em Goi\u00e1s? Goi\u00e1s fica ao lado de Bras\u00edlia. Ele mora em Sergipe<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Voc\u00ea vai no Mato Grosso, 60% do territ\u00f3rio est\u00e1 preservado&#8221;, disse \u00c1lvaro Dias na GloboNews. Trope\u00e7ou. Mato Grosso, Mato Grosso do Sul, Goi\u00e1s, Sergipe &amp; cia. dispensam o artigo: Sou de Mato Grosso. Chegamos a Mato Grosso. Gosto de Mato Grosso do Sul. Voc\u00ea mora em Goi\u00e1s? Goi\u00e1s fica ao lado de Bras\u00edlia. Ele mora em Sergipe.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[818,136,817,819,214,216,217,215],"class_list":["post-16627","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-alvaro-dias","tag-artigo","tag-estados","tag-globonews","tag-goias","tag-mato-grosso","tag-mato-grosso-do-sul","tag-sergipe"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16627"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16627\/revisions"}],"predecessor-version":[{"id":16629,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16627\/revisions\/16629"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}