{"id":16409,"date":"2018-06-27T14:32:10","date_gmt":"2018-06-27T17:32:10","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16409"},"modified":"2018-06-27T14:32:10","modified_gmt":"2018-06-27T17:32:10","slug":"implicar-regencia-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/implicar-regencia-2\/","title":{"rendered":"Implicar: reg\u00eancia"},"content":{"rendered":"<p class=\"western\">O verbo implicar tem tr\u00eas empregos. Em dois, ningu\u00e9m tem d\u00favida. Na acep\u00e7\u00e3o de ter implic\u00e2ncia, pede a preposi\u00e7\u00e3o com: O diretor implicou com ele.<\/p>\n<p class=\"western\">Na de comprometer, envolver, \u00e9 a vez do em: A secret\u00e1ria implicou o chefe no esc\u00e2ndalo.<\/p>\n<p class=\"western\">A d\u00favida surge no significado de produzir como consequ\u00eancia. A\u00ed, implicar implica e complica. O verbo parece, mas n\u00e3o \u00e9. No sentido de acarretar consequ\u00eancias, o malandro \u00e9 transitivo direto. N\u00e3o suporta a preposi\u00e7\u00e3o em: Autonomia tamb\u00e9m implica responsabilidade. Defla\u00e7\u00e3o implica recess\u00e3o. Aumento da taxa de juros implica crescimento do deficit p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O verbo implicar tem tr\u00eas empregos. Em dois, ningu\u00e9m tem d\u00favida. Na acep\u00e7\u00e3o de ter implic\u00e2ncia, pede a preposi\u00e7\u00e3o com: O diretor implicou com ele. Na de comprometer, envolver, \u00e9 a vez do em: A secret\u00e1ria implicou o chefe no esc\u00e2ndalo. A d\u00favida surge no significado de produzir como consequ\u00eancia. A\u00ed, implicar implica e complica. O verbo parece, mas n\u00e3o \u00e9. No sentido de acarretar [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[],"class_list":["post-16409","post","type-post","status-publish","format-standard","hentry","category-portugues"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16409"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16409\/revisions"}],"predecessor-version":[{"id":16410,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16409\/revisions\/16410"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}