{"id":16281,"date":"2018-06-14T14:33:10","date_gmt":"2018-06-14T17:33:10","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16281"},"modified":"2018-06-14T14:33:10","modified_gmt":"2018-06-14T17:33:10","slug":"erramos-clareza","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/erramos-clareza\/","title":{"rendered":"Erramos: clareza"},"content":{"rendered":"<p>\u201cPoliciais apreenderam cerca de 50 toneladas de mercadorias roubadas em um galp\u00e3o, no Gama\u201d, escrevemos na p\u00e1g. 16. Ops! Maltratamos a clareza. O texto diz que a mercadoria foi roubada em Galp\u00e3o no Gama. N\u00e3o \u00e9 isso. Eis a informa\u00e7\u00e3o comprometida com a verdade: <i>Policiais apreenderam, <\/i><i>em um galp\u00e3o no Gama,<\/i><i> cerca de 50 toneladas de mercadorias roubadas<\/i>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPoliciais apreenderam cerca de 50 toneladas de mercadorias roubadas em um galp\u00e3o, no Gama\u201d, escrevemos na p\u00e1g. 16. Ops! Maltratamos a clareza. O texto diz que a mercadoria foi roubada em Galp\u00e3o no Gama. N\u00e3o \u00e9 isso. Eis a informa\u00e7\u00e3o comprometida com a verdade: Policiais apreenderam, em um galp\u00e3o no Gama, cerca de 50 toneladas de mercadorias roubadas.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[],"class_list":["post-16281","post","type-post","status-publish","format-standard","hentry","category-portugues"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16281"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16281\/revisions"}],"predecessor-version":[{"id":16282,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16281\/revisions\/16282"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}