{"id":16210,"date":"2018-06-07T16:45:14","date_gmt":"2018-06-07T19:45:14","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=16210"},"modified":"2018-06-07T16:53:08","modified_gmt":"2018-06-07T19:53:08","slug":"convite-os-deuses-e-lingua","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/convite-os-deuses-e-lingua\/","title":{"rendered":"Convite"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses.jpg\" rel=\"attachment wp-att-16211\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16211\" src=\"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-1024x576.jpg\" alt=\"Os deuses e a l\u00edngua\" width=\"567\" height=\"319\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses.jpg 1024w, https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-300x169.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-768x432.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-350x197.jpg 350w, https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-550x309.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-content\/uploads\/sites\/8\/2018\/06\/livro-deuses-230x129.jpg 230w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/p>\n<p>\u00c9 uma aula espet\u00e1culo cheia de encantos \u2014 com conta\u00e7\u00e3o de hist\u00f3rias, m\u00fasica, v\u00eddeos e muitas curiosidades sobre a mitologia greco-romana e a l\u00edngua portuguesa. V\u00e1 l\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 uma aula espet\u00e1culo cheia de encantos \u2014 com conta\u00e7\u00e3o de hist\u00f3rias, m\u00fasica, v\u00eddeos e muitas curiosidades sobre a mitologia greco-romana e a l\u00edngua portuguesa. V\u00e1 l\u00e1.<\/p>\n","protected":false},"author":25,"featured_media":16211,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[397,399,398,191,400,396],"class_list":["post-16210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portugues","tag-aula-espetaculo","tag-dad-squarisi","tag-feira-do-livro-brasilia","tag-mitologia","tag-mitologia-e-lingua-portuguesa","tag-palestra"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=16210"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16210\/revisions"}],"predecessor-version":[{"id":16214,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/16210\/revisions\/16214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media\/16211"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=16210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=16210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=16210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}