{"id":158,"date":"2015-02-24T12:00:00","date_gmt":"2015-02-24T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/02\/24\/leitor_pergunta-11\/"},"modified":"2015-11-12T19:42:49","modified_gmt":"2015-11-12T21:42:49","slug":"leitor_pergunta-11","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-11\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<p><b> <\/b> Gosto de caqui. A frutinha desce macia e redonda. Gosto,  tamb\u00e9m, de cal\u00e7a c\u00e1qui. O estilo alfaiataria tem classe, charme e  eleg\u00e2ncia.&nbsp;Mas nem tudo s\u00e3o flores. Ao escrever as duas  prefer\u00eancias, paro, penso e me confundo. Por que uma tem acento e a outra n\u00e3o? (Lu\u00edza In\u00eas Gales)  <\/p>\n<p> O grampinho tem a ver com o acento t\u00f4nico da palavra. Em  <i>caqui<\/i>, a fortona \u00e9 a \u00faltima s\u00edlaba. Em <i>c\u00e1qui<\/i>, a  pen\u00faltima:  <\/p>\n<p>1. As ox\u00edtonas terminadas em <b>i<\/b> agradecem, mas  dispensam o acento gr\u00e1fico: <i>tupi, guarani, aqui, ali, abacaxis, jabutis,  parti-lo, dividi-lo<\/i>.  <\/p>\n<p>2. As parox\u00edtonas se op\u00f5em \u00e0s ox\u00edtonas. O que acontece com  umas n\u00e3o acontece com as outras. Ora, se as ox\u00edtonas esnobam o grampinho, as  parox\u00edtonas orgulham-se de exibi-lo. \u00c9 o caso de t\u00e1xi, m\u00e1xi e c\u00e1qui.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gosto de caqui. A frutinha desce macia e redonda. Gosto, tamb\u00e9m, de cal\u00e7a c\u00e1qui. O estilo alfaiataria tem classe, charme e eleg\u00e2ncia.&nbsp;Mas nem tudo s\u00e3o flores. Ao escrever as duas prefer\u00eancias, paro, penso e me confundo. Por que uma tem acento e a outra n\u00e3o? (Lu\u00edza In\u00eas Gales) O grampinho tem a ver com o acento t\u00f4nico da palavra. Em caqui, a fortona \u00e9 a [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-158","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=158"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/158\/revisions"}],"predecessor-version":[{"id":1288,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/158\/revisions\/1288"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}