{"id":12252,"date":"2016-11-30T00:47:29","date_gmt":"2016-11-30T02:47:29","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=12252"},"modified":"2016-11-28T23:49:37","modified_gmt":"2016-11-29T01:49:37","slug":"merito","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/merito\/","title":{"rendered":"M\u00e9rito"},"content":{"rendered":"<p><strong>\u00a0<\/strong>\u00c9 excel\u00eancia pra l\u00e1, excel\u00eancia pra c\u00e1. Magn\u00edfico pra l\u00e1, magn\u00edfico pra c\u00e1. Merit\u00edssimo pra l\u00e1, merit\u00edssimo pra c\u00e1. Ops! Merit\u00edssimo \u00e9 o tratamento dado a juiz. Cuidado com a troca de letra. Se voc\u00ea disser ou escrever \u201cmeret\u00edssimo\u201d, ofende Sua Excel\u00eancia. O pobre ezinho no lugar errado lembra meretriz. \u00c9 cadeia certa.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00c9 excel\u00eancia pra l\u00e1, excel\u00eancia pra c\u00e1. Magn\u00edfico pra l\u00e1, magn\u00edfico pra c\u00e1. Merit\u00edssimo pra l\u00e1, merit\u00edssimo pra c\u00e1. Ops! Merit\u00edssimo \u00e9 o tratamento dado a juiz. Cuidado com a troca de letra. Se voc\u00ea disser ou escrever \u201cmeret\u00edssimo\u201d, ofende Sua Excel\u00eancia. O pobre ezinho no lugar errado lembra meretriz. \u00c9 cadeia certa. \u00a0 &nbsp;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[],"class_list":["post-12252","post","type-post","status-publish","format-standard","hentry","category-portugues"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=12252"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12252\/revisions"}],"predecessor-version":[{"id":12253,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12252\/revisions\/12253"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=12252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=12252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=12252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}