{"id":12140,"date":"2016-11-10T15:12:52","date_gmt":"2016-11-10T17:12:52","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=12140"},"modified":"2016-11-10T15:12:52","modified_gmt":"2016-11-10T17:12:52","slug":"quem-e-quem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/quem-e-quem\/","title":{"rendered":"Quem \u00e9 quem"},"content":{"rendered":"<p>O <em>quem<\/em> \u00e9 um pronome pra l\u00e1 de elitista. Adora gente. E s\u00f3 gente. Sempre que aparece, fala de pessoas: <em>Quem chegou? N\u00e3o sei quem chegou. Foi Maria quem chegou?<\/em><\/p>\n<p>Simples, n\u00e3o? Mas o mundo \u00e9 cheio de maldades. Ou de descuidados. Com frequ\u00eancia, as pessoas sem cora\u00e7\u00e3o agridem o <em>quem<\/em>. Uma das viol\u00eancias contra o pobrezinho \u00e9 empreg\u00e1-lo em frases como estas:<\/p>\n<p><em>Foi o Minist\u00e9rio da Fazenda quem recebeu a atribui\u00e7\u00e3o.<\/em><\/p>\n<p><em>\u00c9 a UnB quem divulga o n\u00famero de vagas adicionais do pr\u00f3ximo semestre.<\/em><\/p>\n<p><strong>Trope\u00e7o<\/strong><\/p>\n<p>Entidades n\u00e3o s\u00e3o pessoas. Por isso constru\u00e7\u00f5es como essas pegam mal como bater em mulher. Comprometem a reputa\u00e7\u00e3o at\u00e9 de Deus. A boa forma recorre ao pronome <em>que<\/em>:<\/p>\n<p><em>Foi o Minist\u00e9rio da Fazenda que recebeu a atribui\u00e7\u00e3o. <\/em><\/p>\n<p><em>\u00c9 a UnB que divulga o n\u00famero de vagas adicionais do pr\u00f3ximo semestre. <\/em><\/p>\n<p><strong>Mais <\/strong><\/p>\n<p>H\u00e1 outra viol\u00eancia muito comum. Volta e meia o <em>quem<\/em> aparece em textos acompanhado da preposi\u00e7\u00e3o a. Disfar\u00e7ado. Como quem n\u00e3o quer nada:<\/p>\n<p><em>O Senado Federal, a quem compete autorizar empr\u00e9stimos externos, \u00e9 composto de 81membros. <\/em><\/p>\n<p>Cruz credo! Benza-nos Deus. O Senado Federal n\u00e3o \u00e9 pessoa. O <em>quem<\/em> fica longe dele. X\u00f4! D\u00ea a vez do pronome <em>o qual<\/em>:<\/p>\n<p><em>O Senado Federal, ao qual compete autorizar empr\u00e9stimos externos, \u00e9 composto de 81membros.<\/em><\/p>\n<p><strong>Guarde isto<\/strong><\/p>\n<p>O pronome quem s\u00f3 gosta de gente.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O quem \u00e9 um pronome pra l\u00e1 de elitista. Adora gente. E s\u00f3 gente. Sempre que aparece, fala de pessoas: Quem chegou? N\u00e3o sei quem chegou. Foi Maria quem chegou? Simples, n\u00e3o? Mas o mundo \u00e9 cheio de maldades. Ou de descuidados. Com frequ\u00eancia, as pessoas sem cora\u00e7\u00e3o agridem o quem. Uma das viol\u00eancias contra o pobrezinho \u00e9 empreg\u00e1-lo em frases como estas: Foi o [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[203],"tags":[8,9,285,11,295],"class_list":["post-12140","post","type-post","status-publish","format-standard","hentry","category-portugues","tag-dad","tag-dicas","tag-pronome","tag-que","tag-quem"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=12140"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12140\/revisions"}],"predecessor-version":[{"id":12141,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12140\/revisions\/12141"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=12140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=12140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=12140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}