{"id":12124,"date":"2016-11-09T00:27:21","date_gmt":"2016-11-09T02:27:21","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=12124"},"modified":"2016-11-08T14:06:34","modified_gmt":"2016-11-08T16:06:34","slug":"diquinhas-de-portugues-2","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/diquinhas-de-portugues-2\/","title":{"rendered":"Diquinhas de portugu\u00eas &#8212; folclore 1"},"content":{"rendered":"<p><strong>Iara, a m\u00e3e das \u00e1guas<\/strong><\/p>\n<p>Ela era uma bela \u00edndia que vivia numa tribo l\u00e1 da Amaz\u00f4nia. Na cultura dela, os homens sa\u00edam pra ca\u00e7ar e pescar. As\u00a0 mulheres ficavam mais perto da oca. Cuidavam da casa, dos filhos e da planta\u00e7\u00e3o.<\/p>\n<p>Um dia, o paj\u00e9 mandou Iara colher milho em uma planta\u00e7\u00e3o de outra aldeia. Ela foi cantando e ouvindo o gorjeio dos p\u00e1ssaros. Com calor, banhou-se nas \u00e1guas do rio e depois se deitou pra descansar.<\/p>\n<p>S\u00f3 acordou de noite. Assustada com a escurid\u00e3o e sem saber voltar pra casa, ficou por ali mesmo. Mas duas on\u00e7as famintas correram pra devor\u00e1-la. Desesperada, ela mergulhou no rio e nunca mais apareceu. Virou uma linda sereia que, com o canto, atrai os homens que tamb\u00e9m nunca mais voltam.<\/p>\n<p><strong>Sabia?<\/strong><\/p>\n<p>Gorjeio se escreve com j porque a letra j se parece com o bico dos p\u00e1ssaros.<\/p>\n<p><strong>Sedu\u00e7\u00e3o<\/strong><\/p>\n<p>O <em>canto da sereia<\/em> virou express\u00e3o. Refere-se a algu\u00e9m que usa palavras e truques para alcan\u00e7ar o que quer. Ningu\u00e9m resiste.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iara, a m\u00e3e das \u00e1guas Ela era uma bela \u00edndia que vivia numa tribo l\u00e1 da Amaz\u00f4nia. Na cultura dela, os homens sa\u00edam pra ca\u00e7ar e pescar. As\u00a0 mulheres ficavam mais perto da oca. Cuidavam da casa, dos filhos e da planta\u00e7\u00e3o. Um dia, o paj\u00e9 mandou Iara colher milho em uma planta\u00e7\u00e3o de outra aldeia. Ela foi cantando e ouvindo o gorjeio dos p\u00e1ssaros. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[207,288,189,69],"tags":[],"class_list":["post-12124","post","type-post","status-publish","format-standard","hentry","category-dad","category-dicas-de-portugues","category-diquinhas-de-portugues","category-grafia"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=12124"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12124\/revisions"}],"predecessor-version":[{"id":12125,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12124\/revisions\/12125"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=12124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=12124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=12124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}