{"id":12033,"date":"2016-04-03T12:27:40","date_gmt":"2016-04-03T15:27:40","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=12033"},"modified":"2016-04-03T12:27:40","modified_gmt":"2016-04-03T15:27:40","slug":"a-presidenta","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/a-presidenta\/","title":{"rendered":"A presidenta"},"content":{"rendered":"<p><span style=\"font-family: Arial,sans-serif\">A caminhada do impeachment trouxe \u00e0 tona velha quest\u00e3o que poucos engolem. Desde que Dilma Rousseff ganhou assento no Planalto e pouso no Alvorada, o g\u00eanero mereceu p\u00e1ginas de explica\u00e7\u00f5es, sem-n\u00famero de entrevistas e mont\u00f5es de palpites. Nunca antes na hist\u00f3ria deste pa\u00eds, uma mulher havia chegado l\u00e1. Da\u00ed a d\u00favida. Ela \u00e9 presidente ou presidenta?<\/span><\/p>\n<p><span style=\"font-family: Arial,sans-serif\">Ningu\u00e9m melhor pra responder que o dicion\u00e1rio. O pai de todos n\u00f3s agrada a gregos, troianos e baianos. Abona as duas formas. Dilma, dizem que pressionada pelas feministas, escolheu presidenta. Com o azinho final, daria mais visibilidade ao feminino. A maioria da popula\u00e7\u00e3o estranhou. Esperneou. Criticou. Mas a palavra final pertence ao Aur\u00e9lio, ao Houaiss e \u00e0 Academia Brasileira de Letras. \u00c9 a tal novela: Manda quem pode. Obedece quem tem ju\u00edzo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A caminhada do impeachment trouxe \u00e0 tona velha quest\u00e3o que poucos engolem. Desde que Dilma Rousseff ganhou assento no Planalto e pouso no Alvorada, o g\u00eanero mereceu p\u00e1ginas de explica\u00e7\u00f5es, sem-n\u00famero de entrevistas e mont\u00f5es de palpites. Nunca antes na hist\u00f3ria deste pa\u00eds, uma mulher havia chegado l\u00e1. Da\u00ed a d\u00favida. Ela \u00e9 presidente ou presidenta? Ningu\u00e9m melhor pra responder que o dicion\u00e1rio. O pai [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[150,195],"tags":[8,9,248,144,10,249,250],"class_list":["post-12033","post","type-post","status-publish","format-standard","hentry","category-flexao","category-grafia-grafia","tag-dad","tag-dicas","tag-feminino","tag-flexao","tag-portugues","tag-presidenta","tag-presidente"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=12033"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12033\/revisions"}],"predecessor-version":[{"id":12034,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12033\/revisions\/12034"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=12033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=12033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=12033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}