{"id":120,"date":"2015-02-10T12:00:00","date_gmt":"2015-02-10T12:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/02\/10\/leitor_pergunta-8\/"},"modified":"2015-11-12T19:42:50","modified_gmt":"2015-11-12T21:42:50","slug":"leitor_pergunta-8","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/leitor_pergunta-8\/","title":{"rendered":"Leitor pergunta"},"content":{"rendered":"<div><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\"> <\/b>  <\/p>\n<p>Gosto de not\u00edcias. Por isso n\u00e3o ou\u00e7o m\u00fasica no carro.  Aproveito a viagem para saber as novidades. Mas uma fala me machuca os ouvidos.  Ao anunciar programas, a CBN repete e repete &#8220;a partir de 11 horas, a partir de  sete horas, a partir de 20 horas&#8221;. O que me diz? (Jos\u00e9 Ricardo)  <\/p>\n<p><b style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">  <\/p>\n<p><\/b> As constru\u00e7\u00f5es lingu\u00edsticas s\u00e3o como as pessoas. Algumas  convivem com a solid\u00e3o. Outras precisam de companhia. A indica\u00e7\u00e3o de horas se  enquadra no segundo caso. O n\u00famero vem sempre \u2014 sempre mesmo \u2014 acompanhado de  artigo (\u00e0s 20 horas, a partir das 11h, desde as 7h, das 8h \u00e0s 18h). A CBN n\u00e3o d\u00e1  bola pra exig\u00eancia. As horas choram. Os ouvintes  tamb\u00e9m.<\/div>\n<div style=\"font-family: Verdana,Arial,Helvetica,sans-serif\">\n<p>&nbsp;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gosto de not\u00edcias. Por isso n\u00e3o ou\u00e7o m\u00fasica no carro. Aproveito a viagem para saber as novidades. Mas uma fala me machuca os ouvidos. Ao anunciar programas, a CBN repete e repete &#8220;a partir de 11 horas, a partir de sete horas, a partir de 20 horas&#8221;. O que me diz? (Jos\u00e9 Ricardo) As constru\u00e7\u00f5es lingu\u00edsticas s\u00e3o como as pessoas. Algumas convivem com a solid\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-120","post","type-post","status-publish","format-standard","hentry","category-geral","category-leitor-pergunta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=120"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/120\/revisions"}],"predecessor-version":[{"id":1327,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/120\/revisions\/1327"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}