{"id":12,"date":"2015-01-05T09:00:00","date_gmt":"2015-01-05T09:00:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/2015\/01\/05\/barbas_de_molho\/"},"modified":"2015-10-23T17:10:20","modified_gmt":"2015-10-23T19:10:20","slug":"barbas_de_molho","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/barbas_de_molho\/","title":{"rendered":"Barbas de molho"},"content":{"rendered":"<p><b><a name=\"Save1\"><\/a><\/b>  <\/p>\n<p>Valha-nos, Deus! Mosquitos fazem a festa. Soltos no  mundo, picam criaturas desprevenidas. Um deles \u00e9 velho conhecido nosso. Trata-se  do <i>Aedes aegypti.<\/i> Chegam as chuvas, ele vira manchete. A raz\u00e3o: o inseto  transmite a dengue. N\u00e3o s\u00f3. Tamb\u00e9m transmite a febre amarela urbana. Por sorte,  a amarelona caiu fora das nossas cidades em 1942. Que fique longe pra todo o  sempre.  <\/p>\n<p>Na vida, dizem os pragm\u00e1ticos, nada se perde.  Tudo se aproveita. \u00c9 o caso do inseto malandro. Ele ensina uma manha da l\u00edngua.  \u00c9 a grafia dos nomes cient\u00edficos. Os sofisticados fazem exig\u00eancias. O primeiro  elemento deve ter a inicial mai\u00fascula. O segundo, min\u00fascula. Ambos se escrevem  em it\u00e1lico. Assim: <i>Aedes aegypti, Coffea arabica (<\/i>caf\u00e9<i>), Rhea  americana (<\/i>ema<i>), Aedes albopictus  (<\/i>tigre-asi\u00e1tico)<i>.<\/i><b><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valha-nos, Deus! Mosquitos fazem a festa. Soltos no mundo, picam criaturas desprevenidas. Um deles \u00e9 velho conhecido nosso. Trata-se do Aedes aegypti. Chegam as chuvas, ele vira manchete. A raz\u00e3o: o inseto transmite a dengue. N\u00e3o s\u00f3. Tamb\u00e9m transmite a febre amarela urbana. Por sorte, a amarelona caiu fora das nossas cidades em 1942. Que fique longe pra todo o sempre. Na vida, dizem os [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12","post","type-post","status-publish","format-standard","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12\/revisions"}],"predecessor-version":[{"id":1433,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/12\/revisions\/1433"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=12"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=12"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}