{"id":11903,"date":"2016-03-16T09:04:22","date_gmt":"2016-03-16T12:04:22","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/dad\/?p=11903"},"modified":"2016-03-16T09:04:22","modified_gmt":"2016-03-16T12:04:22","slug":"manoel-de-barros-encantou","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/dad\/manoel-de-barros-encantou\/","title":{"rendered":"Manoel de Barros encantou"},"content":{"rendered":"<p>&#8220;O poeta \u00e9 um ente que lambe as palavras e depois se alucina.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O poeta \u00e9 um ente que lambe as palavras e depois se alucina.&#8221;<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109],"tags":[41,110,112,111],"class_list":["post-11903","post","type-post","status-publish","format-standard","hentry","category-citacao","tag-citacao","tag-manoel-de-barros","tag-palavras","tag-poeta"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/11903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/comments?post=11903"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/11903\/revisions"}],"predecessor-version":[{"id":11904,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/posts\/11903\/revisions\/11904"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/media?parent=11903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/categories?post=11903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/dad\/wp-json\/wp\/v2\/tags?post=11903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}