{"id":282,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/conversandosobrevinho\/tag\/acaraje\/","name":"acaraj\u00e9","slug":"acaraje","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/conversandosobrevinho\/wp-json\/wp\/v2\/tags\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/conversandosobrevinho\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/conversandosobrevinho\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/conversandosobrevinho\/wp-json\/wp\/v2\/posts?tags=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}