{"id":952,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/tag\/alucinacoes\/","name":"alucina\u00e7\u00f5es","slug":"alucinacoes","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags\/952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/posts?tags=952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}