{"id":836,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/tag\/pre-conferencia-nacional-livre-sobre-saude-da-mulher\/","name":"Pr\u00e9-Confer\u00eancia Nacional Livre sobre Sa\u00fade da Mulher","slug":"pre-conferencia-nacional-livre-sobre-saude-da-mulher","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/posts?tags=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}